{"id":31262,"date":"2022-02-10T18:24:14","date_gmt":"2022-02-10T18:24:14","guid":{"rendered":"https:\/\/nueva.encuba.net\/casas\/casa-villa-margarita-playa-guanabo-con-vista-al-mar-y-piscina\/"},"modified":"2023-07-27T14:14:51","modified_gmt":"2023-07-27T14:14:51","slug":"casa-villa-margarita-guanabo-beach-with-sea-view-and-pool","status":"publish","type":"estate_property","link":"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/","title":{"rendered":"Casa Villa Margarita, Guanabo beach. With sea view and pool"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Casa Villa Margarita is a comfortable lodging on the beach of Guanabo, East Havana municipality.<\/p>\n<p>The accommodation has living rooms with TV and reproduction equipment, large terraces with sea view, 4 air-conditioned bedrooms, each with cloakrooms and private bathrooms.<\/p>\n<p>In the courtyard of the house awaits you a refreshing pool and a spacious ranch\u00f3n, ideal for barbecues with family and friends.<\/p>\n<p>Upon request, breakfast, dinner and laundry services are provided at reasonable prices.<br \/>\n[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0073e1;\"><strong><span style=\"font-family: verdana, geneva, sans-serif;\">BOOK HOUSE<\/span><\/strong><\/span><\/p>\n<p>[\/vc_column_text]<style id=\"wpforms-css-vars-40492\">\n\t\t\t\t#wpforms-40492 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-40492\"><form id=\"wpforms-form-40492\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"40492\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/estate_property\/31262\" data-token=\"53e4cd561846e8df6b485ffb924d9d9c\" data-token-time=\"1784101784\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-40492-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-40492-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" aria-errormessage=\"wpforms-40492-field_0-error\" required><label for=\"wpforms-40492-field_0\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-40492-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" aria-errormessage=\"wpforms-40492-field_0-last-error\" required><label for=\"wpforms-40492-field_0-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-40492-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_1\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-40492-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-40492-field_1-error\" required><\/div><div id=\"wpforms-40492-field_7-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_7\">Country <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-40492-field_7\" class=\"wpforms-field-medium wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"1\" name=\"wpforms[fields][7]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Afghanistan\"  class=\"choice-4 depth-1\"  >Afghanistan<\/option><option value=\"Albania\"  class=\"choice-5 depth-1\"  >Albania<\/option><option value=\"Algeria\"  class=\"choice-6 depth-1\"  >Algeria<\/option><option value=\"American Samoa\"  class=\"choice-7 depth-1\"  >American Samoa<\/option><option value=\"Andorra\"  class=\"choice-8 depth-1\"  >Andorra<\/option><option value=\"Angola\"  class=\"choice-9 depth-1\"  >Angola<\/option><option value=\"Anguilla\"  class=\"choice-10 depth-1\"  >Anguilla<\/option><option value=\"Antarctica\"  class=\"choice-11 depth-1\"  >Antarctica<\/option><option value=\"Antigua and Barbuda\"  class=\"choice-12 depth-1\"  >Antigua and Barbuda<\/option><option value=\"Argentina\"  class=\"choice-13 depth-1\"  >Argentina<\/option><option value=\"Armenia\"  class=\"choice-14 depth-1\"  >Armenia<\/option><option value=\"Aruba\"  class=\"choice-15 depth-1\"  >Aruba<\/option><option value=\"Australia\"  class=\"choice-16 depth-1\"  >Australia<\/option><option value=\"Austria\"  class=\"choice-17 depth-1\"  >Austria<\/option><option value=\"Azerbaijan\"  class=\"choice-18 depth-1\"  >Azerbaijan<\/option><option value=\"Bahamas\"  class=\"choice-19 depth-1\"  >Bahamas<\/option><option value=\"Bahrain\"  class=\"choice-20 depth-1\"  >Bahrain<\/option><option value=\"Bangladesh\"  class=\"choice-21 depth-1\"  >Bangladesh<\/option><option value=\"Barbados\"  class=\"choice-22 depth-1\"  >Barbados<\/option><option value=\"Belarus\"  class=\"choice-23 depth-1\"  >Belarus<\/option><option value=\"Belgium\"  class=\"choice-24 depth-1\"  >Belgium<\/option><option value=\"Belize\"  class=\"choice-25 depth-1\"  >Belize<\/option><option value=\"Benin\"  class=\"choice-26 depth-1\"  >Benin<\/option><option value=\"Bermuda\"  class=\"choice-27 depth-1\"  >Bermuda<\/option><option value=\"Bhutan\"  class=\"choice-28 depth-1\"  >Bhutan<\/option><option value=\"Bolivia (Plurinational State of)\"  class=\"choice-29 depth-1\"  >Bolivia (Plurinational State of)<\/option><option value=\"Bonaire, Saint Eustatius and Saba\"  class=\"choice-30 depth-1\"  >Bonaire, Saint Eustatius and Saba<\/option><option value=\"Bosnia and Herzegovina\"  class=\"choice-31 depth-1\"  >Bosnia and Herzegovina<\/option><option value=\"Botswana\"  class=\"choice-32 depth-1\"  >Botswana<\/option><option value=\"Bouvet Island\"  class=\"choice-33 depth-1\"  >Bouvet Island<\/option><option value=\"Brazil\"  class=\"choice-34 depth-1\"  >Brazil<\/option><option value=\"British Indian Ocean Territory\"  class=\"choice-35 depth-1\"  >British Indian Ocean Territory<\/option><option value=\"Brunei Darussalam\"  class=\"choice-36 depth-1\"  >Brunei Darussalam<\/option><option value=\"Bulgaria\"  class=\"choice-37 depth-1\"  >Bulgaria<\/option><option value=\"Burkina Faso\"  class=\"choice-38 depth-1\"  >Burkina Faso<\/option><option value=\"Burundi\"  class=\"choice-39 depth-1\"  >Burundi<\/option><option value=\"Cabo Verde\"  class=\"choice-40 depth-1\"  >Cabo Verde<\/option><option value=\"Cambodia\"  class=\"choice-41 depth-1\"  >Cambodia<\/option><option value=\"Cameroon\"  class=\"choice-42 depth-1\"  >Cameroon<\/option><option value=\"Canada\"  class=\"choice-43 depth-1\"  >Canada<\/option><option value=\"Cayman Islands\"  class=\"choice-44 depth-1\"  >Cayman Islands<\/option><option value=\"Central African Republic\"  class=\"choice-45 depth-1\"  >Central African Republic<\/option><option value=\"Chad\"  class=\"choice-46 depth-1\"  >Chad<\/option><option value=\"Chile\"  class=\"choice-47 depth-1\"  >Chile<\/option><option value=\"China\"  class=\"choice-48 depth-1\"  >China<\/option><option value=\"Christmas Island\"  class=\"choice-49 depth-1\"  >Christmas Island<\/option><option value=\"Cocos (Keeling) Islands\"  class=\"choice-50 depth-1\"  >Cocos (Keeling) Islands<\/option><option value=\"Colombia\"  class=\"choice-51 depth-1\"  >Colombia<\/option><option value=\"Comoros\"  class=\"choice-52 depth-1\"  >Comoros<\/option><option value=\"Congo\"  class=\"choice-53 depth-1\"  >Congo<\/option><option value=\"Congo (Democratic Republic of the)\"  class=\"choice-54 depth-1\"  >Congo (Democratic Republic of the)<\/option><option value=\"Cook Islands\"  class=\"choice-55 depth-1\"  >Cook Islands<\/option><option value=\"Costa Rica\"  class=\"choice-56 depth-1\"  >Costa Rica<\/option><option value=\"Croatia\"  class=\"choice-57 depth-1\"  >Croatia<\/option><option value=\"Cuba\"  class=\"choice-58 depth-1\"  >Cuba<\/option><option value=\"Cura\u00e7ao\"  class=\"choice-59 depth-1\"  >Cura\u00e7ao<\/option><option value=\"Cyprus\"  class=\"choice-60 depth-1\"  >Cyprus<\/option><option value=\"Czech Republic\"  class=\"choice-61 depth-1\"  >Czech Republic<\/option><option value=\"C\u00f4te d&#039;Ivoire\"  class=\"choice-62 depth-1\"  >C\u00f4te d'Ivoire<\/option><option value=\"Denmark\"  class=\"choice-63 depth-1\"  >Denmark<\/option><option value=\"Djibouti\"  class=\"choice-64 depth-1\"  >Djibouti<\/option><option value=\"Dominica\"  class=\"choice-65 depth-1\"  >Dominica<\/option><option value=\"Dominican Republic\"  class=\"choice-66 depth-1\"  >Dominican Republic<\/option><option value=\"Ecuador\"  class=\"choice-67 depth-1\"  >Ecuador<\/option><option value=\"Egypt\"  class=\"choice-68 depth-1\"  >Egypt<\/option><option value=\"El Salvador\"  class=\"choice-69 depth-1\"  >El Salvador<\/option><option value=\"Equatorial Guinea\"  class=\"choice-70 depth-1\"  >Equatorial Guinea<\/option><option value=\"Eritrea\"  class=\"choice-71 depth-1\"  >Eritrea<\/option><option value=\"Estonia\"  class=\"choice-72 depth-1\"  >Estonia<\/option><option value=\"Eswatini (Kingdom of)\"  class=\"choice-73 depth-1\"  >Eswatini (Kingdom of)<\/option><option value=\"Ethiopia\"  class=\"choice-74 depth-1\"  >Ethiopia<\/option><option value=\"Falkland Islands (Malvinas)\"  class=\"choice-75 depth-1\"  >Falkland Islands (Malvinas)<\/option><option value=\"Faroe Islands\"  class=\"choice-76 depth-1\"  >Faroe Islands<\/option><option value=\"Fiji\"  class=\"choice-77 depth-1\"  >Fiji<\/option><option value=\"Finland\"  class=\"choice-78 depth-1\"  >Finland<\/option><option value=\"France\"  class=\"choice-79 depth-1\"  >France<\/option><option value=\"French Guiana\"  class=\"choice-80 depth-1\"  >French Guiana<\/option><option value=\"French Polynesia\"  class=\"choice-81 depth-1\"  >French Polynesia<\/option><option value=\"French Southern Territories\"  class=\"choice-82 depth-1\"  >French Southern Territories<\/option><option value=\"Gabon\"  class=\"choice-83 depth-1\"  >Gabon<\/option><option value=\"Gambia\"  class=\"choice-84 depth-1\"  >Gambia<\/option><option value=\"Georgia\"  class=\"choice-85 depth-1\"  >Georgia<\/option><option value=\"Germany\"  class=\"choice-86 depth-1\"  >Germany<\/option><option value=\"Ghana\"  class=\"choice-87 depth-1\"  >Ghana<\/option><option value=\"Gibraltar\"  class=\"choice-88 depth-1\"  >Gibraltar<\/option><option value=\"Greece\"  class=\"choice-89 depth-1\"  >Greece<\/option><option value=\"Greenland\"  class=\"choice-90 depth-1\"  >Greenland<\/option><option value=\"Grenada\"  class=\"choice-91 depth-1\"  >Grenada<\/option><option value=\"Guadeloupe\"  class=\"choice-92 depth-1\"  >Guadeloupe<\/option><option value=\"Guam\"  class=\"choice-93 depth-1\"  >Guam<\/option><option value=\"Guatemala\"  class=\"choice-94 depth-1\"  >Guatemala<\/option><option value=\"Guernsey\"  class=\"choice-95 depth-1\"  >Guernsey<\/option><option value=\"Guinea\"  class=\"choice-96 depth-1\"  >Guinea<\/option><option value=\"Guinea-Bissau\"  class=\"choice-97 depth-1\"  >Guinea-Bissau<\/option><option value=\"Guyana\"  class=\"choice-98 depth-1\"  >Guyana<\/option><option value=\"Haiti\"  class=\"choice-99 depth-1\"  >Haiti<\/option><option value=\"Heard Island and McDonald Islands\"  class=\"choice-100 depth-1\"  >Heard Island and McDonald Islands<\/option><option value=\"Honduras\"  class=\"choice-101 depth-1\"  >Honduras<\/option><option value=\"Hong Kong\"  class=\"choice-102 depth-1\"  >Hong Kong<\/option><option value=\"Hungary\"  class=\"choice-103 depth-1\"  >Hungary<\/option><option value=\"Iceland\"  class=\"choice-104 depth-1\"  >Iceland<\/option><option value=\"India\"  class=\"choice-105 depth-1\"  >India<\/option><option value=\"Indonesia\"  class=\"choice-106 depth-1\"  >Indonesia<\/option><option value=\"Iran (Islamic Republic of)\"  class=\"choice-107 depth-1\"  >Iran (Islamic Republic of)<\/option><option value=\"Iraq\"  class=\"choice-108 depth-1\"  >Iraq<\/option><option value=\"Ireland (Republic of)\"  class=\"choice-109 depth-1\"  >Ireland (Republic of)<\/option><option value=\"Isle of Man\"  class=\"choice-110 depth-1\"  >Isle of Man<\/option><option value=\"Israel\"  class=\"choice-111 depth-1\"  >Israel<\/option><option value=\"Italy\"  class=\"choice-112 depth-1\"  >Italy<\/option><option value=\"Jamaica\"  class=\"choice-113 depth-1\"  >Jamaica<\/option><option value=\"Japan\"  class=\"choice-114 depth-1\"  >Japan<\/option><option value=\"Jersey\"  class=\"choice-115 depth-1\"  >Jersey<\/option><option value=\"Jordan\"  class=\"choice-116 depth-1\"  >Jordan<\/option><option value=\"Kazakhstan\"  class=\"choice-117 depth-1\"  >Kazakhstan<\/option><option value=\"Kenya\"  class=\"choice-118 depth-1\"  >Kenya<\/option><option value=\"Kiribati\"  class=\"choice-119 depth-1\"  >Kiribati<\/option><option value=\"Korea (Democratic People&#039;s Republic of)\"  class=\"choice-120 depth-1\"  >Korea (Democratic People's Republic of)<\/option><option value=\"Korea (Republic of)\"  class=\"choice-121 depth-1\"  >Korea (Republic of)<\/option><option value=\"Kosovo\"  class=\"choice-122 depth-1\"  >Kosovo<\/option><option value=\"Kuwait\"  class=\"choice-123 depth-1\"  >Kuwait<\/option><option value=\"Kyrgyzstan\"  class=\"choice-124 depth-1\"  >Kyrgyzstan<\/option><option value=\"Lao People&#039;s Democratic Republic\"  class=\"choice-125 depth-1\"  >Lao People's Democratic Republic<\/option><option value=\"Latvia\"  class=\"choice-126 depth-1\"  >Latvia<\/option><option value=\"Lebanon\"  class=\"choice-127 depth-1\"  >Lebanon<\/option><option value=\"Lesotho\"  class=\"choice-128 depth-1\"  >Lesotho<\/option><option value=\"Liberia\"  class=\"choice-129 depth-1\"  >Liberia<\/option><option value=\"Libya\"  class=\"choice-130 depth-1\"  >Libya<\/option><option value=\"Liechtenstein\"  class=\"choice-131 depth-1\"  >Liechtenstein<\/option><option value=\"Lithuania\"  class=\"choice-132 depth-1\"  >Lithuania<\/option><option value=\"Luxembourg\"  class=\"choice-133 depth-1\"  >Luxembourg<\/option><option value=\"Macao\"  class=\"choice-134 depth-1\"  >Macao<\/option><option value=\"Madagascar\"  class=\"choice-135 depth-1\"  >Madagascar<\/option><option value=\"Malawi\"  class=\"choice-136 depth-1\"  >Malawi<\/option><option value=\"Malaysia\"  class=\"choice-137 depth-1\"  >Malaysia<\/option><option value=\"Maldives\"  class=\"choice-138 depth-1\"  >Maldives<\/option><option value=\"Mali\"  class=\"choice-139 depth-1\"  >Mali<\/option><option value=\"Malta\"  class=\"choice-140 depth-1\"  >Malta<\/option><option value=\"Marshall Islands\"  class=\"choice-141 depth-1\"  >Marshall Islands<\/option><option value=\"Martinique\"  class=\"choice-142 depth-1\"  >Martinique<\/option><option value=\"Mauritania\"  class=\"choice-143 depth-1\"  >Mauritania<\/option><option value=\"Mauritius\"  class=\"choice-144 depth-1\"  >Mauritius<\/option><option value=\"Mayotte\"  class=\"choice-145 depth-1\"  >Mayotte<\/option><option value=\"Mexico\"  class=\"choice-146 depth-1\"  >Mexico<\/option><option value=\"Micronesia (Federated States of)\"  class=\"choice-147 depth-1\"  >Micronesia (Federated States of)<\/option><option value=\"Moldova (Republic of)\"  class=\"choice-148 depth-1\"  >Moldova (Republic of)<\/option><option value=\"Monaco\"  class=\"choice-149 depth-1\"  >Monaco<\/option><option value=\"Mongolia\"  class=\"choice-150 depth-1\"  >Mongolia<\/option><option value=\"Montenegro\"  class=\"choice-151 depth-1\"  >Montenegro<\/option><option value=\"Montserrat\"  class=\"choice-152 depth-1\"  >Montserrat<\/option><option value=\"Morocco\"  class=\"choice-153 depth-1\"  >Morocco<\/option><option value=\"Mozambique\"  class=\"choice-154 depth-1\"  >Mozambique<\/option><option value=\"Myanmar\"  class=\"choice-155 depth-1\"  >Myanmar<\/option><option value=\"Namibia\"  class=\"choice-156 depth-1\"  >Namibia<\/option><option value=\"Nauru\"  class=\"choice-157 depth-1\"  >Nauru<\/option><option value=\"Nepal\"  class=\"choice-158 depth-1\"  >Nepal<\/option><option value=\"Netherlands\"  class=\"choice-159 depth-1\"  >Netherlands<\/option><option value=\"New Caledonia\"  class=\"choice-160 depth-1\"  >New Caledonia<\/option><option value=\"New Zealand\"  class=\"choice-161 depth-1\"  >New Zealand<\/option><option value=\"Nicaragua\"  class=\"choice-162 depth-1\"  >Nicaragua<\/option><option value=\"Niger\"  class=\"choice-163 depth-1\"  >Niger<\/option><option value=\"Nigeria\"  class=\"choice-164 depth-1\"  >Nigeria<\/option><option value=\"Niue\"  class=\"choice-165 depth-1\"  >Niue<\/option><option value=\"Norfolk Island\"  class=\"choice-166 depth-1\"  >Norfolk Island<\/option><option value=\"North Macedonia (Republic of)\"  class=\"choice-167 depth-1\"  >North Macedonia (Republic of)<\/option><option value=\"Northern Mariana Islands\"  class=\"choice-168 depth-1\"  >Northern Mariana Islands<\/option><option value=\"Norway\"  class=\"choice-169 depth-1\"  >Norway<\/option><option value=\"Oman\"  class=\"choice-170 depth-1\"  >Oman<\/option><option value=\"Pakistan\"  class=\"choice-171 depth-1\"  >Pakistan<\/option><option value=\"Palau\"  class=\"choice-172 depth-1\"  >Palau<\/option><option value=\"Palestine (State of)\"  class=\"choice-173 depth-1\"  >Palestine (State of)<\/option><option value=\"Panama\"  class=\"choice-174 depth-1\"  >Panama<\/option><option value=\"Papua New Guinea\"  class=\"choice-175 depth-1\"  >Papua New Guinea<\/option><option value=\"Paraguay\"  class=\"choice-176 depth-1\"  >Paraguay<\/option><option value=\"Peru\"  class=\"choice-177 depth-1\"  >Peru<\/option><option value=\"Philippines\"  class=\"choice-178 depth-1\"  >Philippines<\/option><option value=\"Pitcairn\"  class=\"choice-179 depth-1\"  >Pitcairn<\/option><option value=\"Poland\"  class=\"choice-180 depth-1\"  >Poland<\/option><option value=\"Portugal\"  class=\"choice-181 depth-1\"  >Portugal<\/option><option value=\"Puerto Rico\"  class=\"choice-182 depth-1\"  >Puerto Rico<\/option><option value=\"Qatar\"  class=\"choice-183 depth-1\"  >Qatar<\/option><option value=\"Romania\"  class=\"choice-184 depth-1\"  >Romania<\/option><option value=\"Russian Federation\"  class=\"choice-185 depth-1\"  >Russian Federation<\/option><option value=\"Rwanda\"  class=\"choice-186 depth-1\"  >Rwanda<\/option><option value=\"R\u00e9union\"  class=\"choice-187 depth-1\"  >R\u00e9union<\/option><option value=\"Saint Barth\u00e9lemy\"  class=\"choice-188 depth-1\"  >Saint Barth\u00e9lemy<\/option><option value=\"Saint Helena, Ascension and Tristan da Cunha\"  class=\"choice-189 depth-1\"  >Saint Helena, Ascension and Tristan da Cunha<\/option><option value=\"Saint Kitts and Nevis\"  class=\"choice-190 depth-1\"  >Saint Kitts and Nevis<\/option><option value=\"Saint Lucia\"  class=\"choice-191 depth-1\"  >Saint Lucia<\/option><option value=\"Saint Martin (French part)\"  class=\"choice-192 depth-1\"  >Saint Martin (French part)<\/option><option value=\"Saint Pierre and Miquelon\"  class=\"choice-193 depth-1\"  >Saint Pierre and Miquelon<\/option><option value=\"Saint Vincent and the Grenadines\"  class=\"choice-194 depth-1\"  >Saint Vincent and the Grenadines<\/option><option value=\"Samoa\"  class=\"choice-195 depth-1\"  >Samoa<\/option><option value=\"San Marino\"  class=\"choice-196 depth-1\"  >San Marino<\/option><option value=\"Sao Tome and Principe\"  class=\"choice-197 depth-1\"  >Sao Tome and Principe<\/option><option value=\"Saudi Arabia\"  class=\"choice-198 depth-1\"  >Saudi Arabia<\/option><option value=\"Senegal\"  class=\"choice-199 depth-1\"  >Senegal<\/option><option value=\"Serbia\"  class=\"choice-200 depth-1\"  >Serbia<\/option><option value=\"Seychelles\"  class=\"choice-201 depth-1\"  >Seychelles<\/option><option value=\"Sierra Leone\"  class=\"choice-202 depth-1\"  >Sierra Leone<\/option><option value=\"Singapore\"  class=\"choice-203 depth-1\"  >Singapore<\/option><option value=\"Sint Maarten (Dutch part)\"  class=\"choice-204 depth-1\"  >Sint Maarten (Dutch part)<\/option><option value=\"Slovakia\"  class=\"choice-205 depth-1\"  >Slovakia<\/option><option value=\"Slovenia\"  class=\"choice-206 depth-1\"  >Slovenia<\/option><option value=\"Solomon Islands\"  class=\"choice-207 depth-1\"  >Solomon Islands<\/option><option value=\"Somalia\"  class=\"choice-208 depth-1\"  >Somalia<\/option><option value=\"South Africa\"  class=\"choice-209 depth-1\"  >South Africa<\/option><option value=\"South Georgia and the South Sandwich Islands\"  class=\"choice-210 depth-1\"  >South Georgia and the South Sandwich Islands<\/option><option value=\"South Sudan\"  class=\"choice-211 depth-1\"  >South Sudan<\/option><option value=\"Spain\"  class=\"choice-212 depth-1\"  >Spain<\/option><option value=\"Sri Lanka\"  class=\"choice-213 depth-1\"  >Sri Lanka<\/option><option value=\"Sudan\"  class=\"choice-214 depth-1\"  >Sudan<\/option><option value=\"Suriname\"  class=\"choice-215 depth-1\"  >Suriname<\/option><option value=\"Svalbard and Jan Mayen\"  class=\"choice-216 depth-1\"  >Svalbard and Jan Mayen<\/option><option value=\"Sweden\"  class=\"choice-217 depth-1\"  >Sweden<\/option><option value=\"Switzerland\"  class=\"choice-218 depth-1\"  >Switzerland<\/option><option value=\"Syrian Arab Republic\"  class=\"choice-219 depth-1\"  >Syrian Arab Republic<\/option><option value=\"Taiwan, Republic of China\"  class=\"choice-220 depth-1\"  >Taiwan, Republic of China<\/option><option value=\"Tajikistan\"  class=\"choice-221 depth-1\"  >Tajikistan<\/option><option value=\"Tanzania (United Republic of)\"  class=\"choice-222 depth-1\"  >Tanzania (United Republic of)<\/option><option value=\"Thailand\"  class=\"choice-223 depth-1\"  >Thailand<\/option><option value=\"Timor-Leste\"  class=\"choice-224 depth-1\"  >Timor-Leste<\/option><option value=\"Togo\"  class=\"choice-225 depth-1\"  >Togo<\/option><option value=\"Tokelau\"  class=\"choice-226 depth-1\"  >Tokelau<\/option><option value=\"Tonga\"  class=\"choice-227 depth-1\"  >Tonga<\/option><option value=\"Trinidad and Tobago\"  class=\"choice-228 depth-1\"  >Trinidad and Tobago<\/option><option value=\"Tunisia\"  class=\"choice-229 depth-1\"  >Tunisia<\/option><option value=\"Turkey\"  class=\"choice-230 depth-1\"  >Turkey<\/option><option value=\"Turkmenistan\"  class=\"choice-231 depth-1\"  >Turkmenistan<\/option><option value=\"Turks and Caicos Islands\"  class=\"choice-232 depth-1\"  >Turks and Caicos Islands<\/option><option value=\"Tuvalu\"  class=\"choice-233 depth-1\"  >Tuvalu<\/option><option value=\"Uganda\"  class=\"choice-234 depth-1\"  >Uganda<\/option><option value=\"Ukraine\"  class=\"choice-235 depth-1\"  >Ukraine<\/option><option value=\"United Arab Emirates\"  class=\"choice-236 depth-1\"  >United Arab Emirates<\/option><option value=\"United Kingdom of Great Britain and Northern Ireland\"  class=\"choice-237 depth-1\"  >United Kingdom of Great Britain and Northern Ireland<\/option><option value=\"United States Minor Outlying Islands\"  class=\"choice-238 depth-1\"  >United States Minor Outlying Islands<\/option><option value=\"United States of America\"  class=\"choice-239 depth-1\"  >United States of America<\/option><option value=\"Uruguay\"  class=\"choice-240 depth-1\"  >Uruguay<\/option><option value=\"Uzbekistan\"  class=\"choice-241 depth-1\"  >Uzbekistan<\/option><option value=\"Vanuatu\"  class=\"choice-242 depth-1\"  >Vanuatu<\/option><option value=\"Vatican City State\"  class=\"choice-243 depth-1\"  >Vatican City State<\/option><option value=\"Venezuela (Bolivarian Republic of)\"  class=\"choice-244 depth-1\"  >Venezuela (Bolivarian Republic of)<\/option><option value=\"Vietnam\"  class=\"choice-245 depth-1\"  >Vietnam<\/option><option value=\"Virgin Islands (British)\"  class=\"choice-246 depth-1\"  >Virgin Islands (British)<\/option><option value=\"Virgin Islands (U.S.)\"  class=\"choice-247 depth-1\"  >Virgin Islands (U.S.)<\/option><option value=\"Wallis and Futuna\"  class=\"choice-248 depth-1\"  >Wallis and Futuna<\/option><option value=\"Western Sahara\"  class=\"choice-249 depth-1\"  >Western Sahara<\/option><option value=\"Yemen\"  class=\"choice-250 depth-1\"  >Yemen<\/option><option value=\"Zambia\"  class=\"choice-251 depth-1\"  >Zambia<\/option><option value=\"Zimbabwe\"  class=\"choice-252 depth-1\"  >Zimbabwe<\/option><option value=\"\u00c5land Islands\"  class=\"choice-253 depth-1\"  >\u00c5land Islands<\/option><\/select><\/div><div id=\"wpforms-40492-field_61-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"61\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_61\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-40492-field_61\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][61]\" aria-label=\"Phone\" aria-errormessage=\"wpforms-40492-field_61-error\" required><\/div><div id=\"wpforms-40492-field_4-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_4\">Entry date <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-40492-field_4\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][4][date]\" aria-errormessage=\"wpforms-40492-field_4-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-40492-field_5-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_5\">Departure date <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-40492-field_5\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][5][date]\" aria-errormessage=\"wpforms-40492-field_5-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-40492-field_6-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_6\">Number of beds <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-40492-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" step=\"any\" aria-errormessage=\"wpforms-40492-field_6-error\" required><\/div><div id=\"wpforms-40492-field_8-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_8\">Amount of people <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-40492-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" step=\"any\" aria-errormessage=\"wpforms-40492-field_8-error\" required><\/div><div id=\"wpforms-40492-field_9-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_9\">Number of rooms <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-40492-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" step=\"any\" aria-errormessage=\"wpforms-40492-field_9-error\" required><\/div><div id=\"wpforms-40492-field_16-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-trigger\" data-field-id=\"16\"><fieldset><legend class=\"wpforms-field-label\">Airport Pickup<\/legend><ul id=\"wpforms-40492-field_16\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-40492-field_16_1\" name=\"wpforms[fields][16]\" value=\"Yes\" aria-errormessage=\"wpforms-40492-field_16_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_16_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-40492-field_16_2\" name=\"wpforms[fields][16]\" value=\"No\" aria-errormessage=\"wpforms-40492-field_16_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_16_2\">No<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-40492-field_23-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"23\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_23\">Airline and Flight Number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-40492-field_23\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][23]\" aria-errormessage=\"wpforms-40492-field_23-error\" required><\/div><div id=\"wpforms-40492-field_24-container\" class=\"wpforms-field wpforms-field-number-slider wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"24\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_24\">Number of passengers<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-40492-field_24\" class=\"wpforms-field-medium\" name=\"wpforms[fields][24]\" value=\"1\" aria-errormessage=\"wpforms-40492-field_24-error\"\t\tmin=\"1\"\n\tmax=\"10\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Valor seleccionado: {value}\">\n\tValor seleccionado: <b>1<\/b><\/div>\n<\/div><div id=\"wpforms-40492-field_25-container\" class=\"wpforms-field wpforms-field-date-time wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"25\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Date and Time of Collection <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-date-type-datepicker\"><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-40492-field_25\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][25][date]\" aria-errormessage=\"wpforms-40492-field_25-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><label for=\"wpforms-40492-field_25\" class=\"wpforms-field-sublabel after\">Date<\/label><\/div><div class=\"wpforms-field-row-block\"><input type=\"text\" id=\"wpforms-40492-field_25-time\" class=\"wpforms-field-date-time-time wpforms-timepicker wpforms-field-required\" data-time-format=\"g:i A\" data-step=\"30\" data-rule-time12h=\"true\" name=\"wpforms[fields][25][time]\" aria-errormessage=\"wpforms-40492-field_25-time-error\" required><label for=\"wpforms-40492-field_25-time\" class=\"wpforms-field-sublabel after\">Time<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-40492-field_54-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"54\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_54\">Destination address <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-40492-field_54\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][54]\" aria-errormessage=\"wpforms-40492-field_54-error\" required><\/div><div id=\"wpforms-40492-field_19-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-trigger\" data-field-id=\"19\"><fieldset><legend class=\"wpforms-field-label\">Do you want to organize an event? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-40492-field_19\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-40492-field_19_1\" name=\"wpforms[fields][19]\" value=\"Yes\" aria-errormessage=\"wpforms-40492-field_19_1-error\" aria-describedby=\"wpforms-40492-field_19-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_19_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-40492-field_19_2\" name=\"wpforms[fields][19]\" value=\"No\" aria-errormessage=\"wpforms-40492-field_19_2-error\" aria-describedby=\"wpforms-40492-field_19-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_19_2\">No<\/label><\/li><\/ul><div id=\"wpforms-40492-field_19-description\" class=\"wpforms-field-description\">Wedding, 15-year-old party, children's birthday, business event, private party, etc.<\/div><\/fieldset><\/div><div id=\"wpforms-40492-field_20-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-field wpforms-conditional-show wpforms-field-select-style-classic\" data-field-id=\"20\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_20\">Event type <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-40492-field_20\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][20]\" required=\"required\"><option value=\"Wedding, Renewal of Vows\"  class=\"choice-4 depth-1\"  >Wedding, Renewal of Vows<\/option><option value=\"Bachelor party\"  class=\"choice-5 depth-1\"  >Bachelor party<\/option><option value=\"Honeymoon\"  class=\"choice-6 depth-1\"  >Honeymoon<\/option><option value=\"Business Event - Business\"  class=\"choice-7 depth-1\"  >Business Event - Business<\/option><option value=\"Private Event - Party\"  class=\"choice-8 depth-1\"  >Private Event - Party<\/option><option value=\"15th birthday party\"  class=\"choice-9 depth-1\"  >15th birthday party<\/option><option value=\"Children&#039;s Birthday\"  class=\"choice-10 depth-1\"  >Children's Birthday<\/option><option value=\"baby shower\"  class=\"choice-11 depth-1\"  >baby shower<\/option><option value=\"Other\"  class=\"choice-12 depth-1\"  >Other<\/option><\/select><\/div><div id=\"wpforms-40492-field_21-container\" class=\"wpforms-field wpforms-field-date-time wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"21\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_21\">Event Date <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-40492-field_21\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][21][date]\" aria-errormessage=\"wpforms-40492-field_21-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-40492-field_59-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"59\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Event Services <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-40492-field_59\" class=\"wpforms-field-required\"><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_4\" name=\"wpforms[fields][59][]\" value=\"Decor\" aria-errormessage=\"wpforms-40492-field_59_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_4\">Decor<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_5\" name=\"wpforms[fields][59][]\" value=\"Event organization\" aria-errormessage=\"wpforms-40492-field_59_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_5\">Event organization<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_6\" name=\"wpforms[fields][59][]\" value=\"buffet\" aria-errormessage=\"wpforms-40492-field_59_6-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_6\">buffet<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_7\" name=\"wpforms[fields][59][]\" value=\"Dinner\" aria-errormessage=\"wpforms-40492-field_59_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_7\">Dinner<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_8\" name=\"wpforms[fields][59][]\" value=\"Stylist\" aria-errormessage=\"wpforms-40492-field_59_8-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_8\">Stylist<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_9\" name=\"wpforms[fields][59][]\" value=\"Master of ceremony\" aria-errormessage=\"wpforms-40492-field_59_9-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_9\">Master of ceremony<\/label><\/li><li class=\"choice-10 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_10\" name=\"wpforms[fields][59][]\" value=\"Cake shop\" aria-errormessage=\"wpforms-40492-field_59_10-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_10\">Cake shop<\/label><\/li><li class=\"choice-11 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_11\" name=\"wpforms[fields][59][]\" value=\"Photography\" aria-errormessage=\"wpforms-40492-field_59_11-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_11\">Photography<\/label><\/li><li class=\"choice-12 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_12\" name=\"wpforms[fields][59][]\" value=\"Video\" aria-errormessage=\"wpforms-40492-field_59_12-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_12\">Video<\/label><\/li><li class=\"choice-13 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_13\" name=\"wpforms[fields][59][]\" value=\"Recorded Music- Dj\" aria-errormessage=\"wpforms-40492-field_59_13-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_13\">Recorded Music- Dj<\/label><\/li><li class=\"choice-14 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_14\" name=\"wpforms[fields][59][]\" value=\"Band\" aria-errormessage=\"wpforms-40492-field_59_14-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_14\">Band<\/label><\/li><li class=\"choice-15 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_15\" name=\"wpforms[fields][59][]\" value=\"Suits\" aria-errormessage=\"wpforms-40492-field_59_15-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_15\">Suits<\/label><\/li><li class=\"choice-16 depth-1\"><input type=\"checkbox\" id=\"wpforms-40492-field_59_16\" name=\"wpforms[fields][59][]\" value=\"Transport\" aria-errormessage=\"wpforms-40492-field_59_16-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-40492-field_59_16\">Transport<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-40492-field_62-container\" class=\"wpforms-field wpforms-field-captcha\" data-field-id=\"62\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_62\">Solve <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label>\t\t\t<div class=\"wpforms-captcha-math\">\n\t\t\t\t<span id=\"wpforms-40492-field_62-question\" class=\"wpforms-captcha-equation\">\n\t\t\t\t\t<span class=\"n1\">3<\/span>\n\t\t\t\t\t\t\t<span class=\"cal\">*<\/span>\n\t\t\t\t\t\t\t<span class=\"n2\">10<\/span>\t\t\t\t\t<span class=\"e\">=<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<input type=\"text\" id=\"wpforms-40492-field_62\" class=\"wpforms-field-medium wpforms-field-required a\" data-rule-wpf-captcha=\"math\" data-is-wrapped-field=\"1\" name=\"wpforms[fields][62][a]\" aria-errormessage=\"wpforms-40492-field_62-error\" aria-describedby=\"wpforms-40492-field_62-question\" required>\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][62][cal]\" class=\"cal\">\n\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][62][n2]\" class=\"n2\">\n\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][62][n1]\" class=\"n1\">\n\t\t\t<\/div>\n\t\t\t<\/div><div id=\"wpforms-40492-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-40492-field_2\">Message <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-40492-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-40492-field_2-error\" required><\/textarea><\/div><div id=\"wpforms-40492-field_60-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"60\"><div id=\"wpforms-40492-field_60\" aria-errormessage=\"wpforms-40492-field_60-error\"><div id=\"wpforms-40399-field_58-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"58\">\r\n\t<ul id=\"wpforms-40399-field_58\" class=\"wpforms-field-required\">\r\n\t\t<li class=\"choice-1 wpforms-selected\">\r\n\t\t<input type=\"checkbox\" id=\"wpforms-40399-field_58_1\" name=\"wpforms[fields][58][]\" value=\"Doy mi consentimiento para que esta web almacene la informaci\u00f3n que env\u00edo para que puedan responder a mi petici\u00f3n.\" aria-errormessage=\"wpforms-40399-field_58_1-error\" required=\"\" class=\"wpforms-valid\" aria-invalid=\"false\" aria-describedby=\"wpforms[fields][58][]-error\" checked\/>\r\n\t\t<label class=\"wpforms-field-label\" for=\"wpforms-40399-field_58\">Acepto las  <a href=\"https:\/\/encuba.net\/en\/conditions-of-use-and-privacy-policies-encuba-net\/\" target=\"_blank\">Condiciones de Uso o Pol\u00edticas de Privacidad<\/a> del sitio<\/label><span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span>\r\n\t\t<\/li>\r\n\t<\/ul>\r\n<\/div>\r\n<\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"40492\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/estate_property\/31262\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-40492\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img decoding=\"async\" data-src=\"https:\/\/encuba.net\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner lazyload\" style=\"--smush-placeholder-width: 26px; --smush-placeholder-aspect-ratio: 26\/26;display: none;\" width=\"26\" height=\"26\" alt=\"Loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Casa Villa Margarita is a comfortable lodging on the beach of Guanabo, East Havana municipality. The accommodation has living rooms with TV and reproduction equipment, large terraces with sea view, 4 air-conditioned bedrooms, each with cloakrooms and private bathrooms. In the courtyard of the house awaits you a refreshing pool and a spacious ranch\u00f3n, ideal for barbecues with family and friends. Upon request, breakfast, &#8230;<\/p>\n","protected":false},"featured_media":31260,"comment_status":"open","ping_status":"closed","template":"","property_category":[214,219,183,308,215],"property_action_category":[],"property_city":[],"property_area":[],"property_county_state":[],"property_features":[],"property_status":[],"class_list":["post-31262","estate_property","type-estate_property","status-publish","has-post-thumbnail","hentry","property_category-casas-con-piscina-en-2","property_category-guanabo-en-2","property_category-la-habana-en-2","property_category-piscina-en-guanabo-en","property_category-playas-del-este-en-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa Villa Margarita, Guanabo beach. With sea view and pool<\/title>\n<meta name=\"description\" content=\"Casa Villa Margarita, Guanabo beach, East Havana. Comfortable accommodation with sea view, pool and ranch\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa Villa Margarita, Guanabo beach. With sea view and pool\" \/>\n<meta property=\"og:description\" content=\"Casa Villa Margarita, Guanabo beach, East Havana. Comfortable accommodation with sea view, pool and ranch\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/\" \/>\n<meta property=\"og:site_name\" content=\"EnCUBA\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-27T14:14:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/encuba.net\/wp-content\/uploads\/2022\/02\/Casa-Villa-Margarita-playa-Guanabo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\\\/\",\"url\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\\\/\",\"name\":\"Casa Villa Margarita, Guanabo beach. With sea view and pool\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Casa-Villa-Margarita-playa-Guanabo.jpg\",\"datePublished\":\"2022-02-10T18:24:14+00:00\",\"dateModified\":\"2023-07-27T14:14:51+00:00\",\"description\":\"Casa Villa Margarita, Guanabo beach, East Havana. Comfortable accommodation with sea view, pool and ranch\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\\\/#primaryimage\",\"url\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Casa-Villa-Margarita-playa-Guanabo.jpg\",\"contentUrl\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Casa-Villa-Margarita-playa-Guanabo.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/encuba.net\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Properties\",\"item\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casa Villa Margarita, Guanabo beach. With sea view and pool\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/encuba.net\\\/en\\\/\",\"name\":\"EnCUBA\",\"description\":\"Casas de alquiler en Cuba \ud83c\udfd8\ufe0f Renta de bellas casas particulares, apartamentos, habitaciones, villas y hostales. Reserva gratis y r\u00e1pido AQUI\",\"publisher\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/encuba.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#organization\",\"name\":\"EnCUBA\",\"url\":\"https:\\\/\\\/encuba.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo22.png\",\"contentUrl\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo22.png\",\"width\":192,\"height\":54,\"caption\":\"EnCUBA\"},\"image\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa Villa Margarita, Guanabo beach. With sea view and pool","description":"Casa Villa Margarita, Guanabo beach, East Havana. Comfortable accommodation with sea view, pool and ranch\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/","og_locale":"en_US","og_type":"article","og_title":"Casa Villa Margarita, Guanabo beach. With sea view and pool","og_description":"Casa Villa Margarita, Guanabo beach, East Havana. Comfortable accommodation with sea view, pool and ranch\u00f3n","og_url":"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/","og_site_name":"EnCUBA","article_modified_time":"2023-07-27T14:14:51+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/02\/Casa-Villa-Margarita-playa-Guanabo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/","url":"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/","name":"Casa Villa Margarita, Guanabo beach. With sea view and pool","isPartOf":{"@id":"https:\/\/encuba.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/#primaryimage"},"image":{"@id":"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/#primaryimage"},"thumbnailUrl":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/02\/Casa-Villa-Margarita-playa-Guanabo.jpg","datePublished":"2022-02-10T18:24:14+00:00","dateModified":"2023-07-27T14:14:51+00:00","description":"Casa Villa Margarita, Guanabo beach, East Havana. Comfortable accommodation with sea view, pool and ranch\u00f3n","breadcrumb":{"@id":"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/#primaryimage","url":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/02\/Casa-Villa-Margarita-playa-Guanabo.jpg","contentUrl":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/02\/Casa-Villa-Margarita-playa-Guanabo.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/encuba.net\/en\/houses\/casa-villa-margarita-guanabo-beach-with-sea-view-and-pool\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/encuba.net\/en\/"},{"@type":"ListItem","position":2,"name":"Properties","item":"https:\/\/encuba.net\/en\/houses\/"},{"@type":"ListItem","position":3,"name":"Casa Villa Margarita, Guanabo beach. With sea view and pool"}]},{"@type":"WebSite","@id":"https:\/\/encuba.net\/en\/#website","url":"https:\/\/encuba.net\/en\/","name":"EnCUBA","description":"Casas de alquiler en Cuba \ud83c\udfd8\ufe0f Renta de bellas casas particulares, apartamentos, habitaciones, villas y hostales. Reserva gratis y r\u00e1pido AQUI","publisher":{"@id":"https:\/\/encuba.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encuba.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/encuba.net\/en\/#organization","name":"EnCUBA","url":"https:\/\/encuba.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/encuba.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/04\/logo22.png","contentUrl":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/04\/logo22.png","width":192,"height":54,"caption":"EnCUBA"},"image":{"@id":"https:\/\/encuba.net\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/estate_property\/31262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/estate_property"}],"about":[{"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/types\/estate_property"}],"replies":[{"embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/comments?post=31262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/media\/31260"}],"wp:attachment":[{"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/media?parent=31262"}],"wp:term":[{"taxonomy":"property_category","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_category?post=31262"},{"taxonomy":"property_action_category","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_action_category?post=31262"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_city?post=31262"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_area?post=31262"},{"taxonomy":"property_county_state","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_county_state?post=31262"},{"taxonomy":"property_features","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_features?post=31262"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_status?post=31262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}