{"id":48950,"date":"2025-03-06T19:06:21","date_gmt":"2025-03-06T19:06:21","guid":{"rendered":"https:\/\/encuba.net\/casas\/apartamento-marina-en-playa-3-habitaciones-y-vistas-al-mar\/"},"modified":"2025-03-06T22:00:51","modified_gmt":"2025-03-06T22:00:51","slug":"marina-apartment-in-playa-3-bedrooms-and-sea-views","status":"publish","type":"estate_property","link":"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/","title":{"rendered":"Marina Apartment in Playa, 3 bedrooms and sea views"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]The Apto Marina in Playa is an exclusive property that offers a comfortable and relaxing stay with stunning views of the Hemingway Marina. It has three bedrooms, each equipped with a private bathroom, hot water and minibar, as well as a TV for your entertainment.<\/p>\n<p>The kitchen is independent and perfect for preparing your favorite meals. In addition, it includes a grill to enjoy outdoors and two canoes to explore the surroundings. Beach items are available to make the most of your stay. Its location in Playa is unbeatable, close to restaurants and tourist attractions.[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0073e1;\"><strong><span style=\"font-family: verdana, geneva, sans-serif;\">BOOK HOUSE<\/span><\/strong><\/span><\/p>\n<p>[\/vc_column_text]<style id=\"wpforms-css-vars-29301\">\n\t\t\t\t#wpforms-29301 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-29301\"><form id=\"wpforms-form-29301\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"29301\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/estate_property\/48950\" data-token=\"70829b6122777644815248c055f0a0b8\" data-token-time=\"1784087912\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-29301-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-29301-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" aria-errormessage=\"wpforms-29301-field_0-error\" required><label for=\"wpforms-29301-field_0\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-29301-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" aria-errormessage=\"wpforms-29301-field_0-last-error\" required><label for=\"wpforms-29301-field_0-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-29301-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_1\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-29301-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-29301-field_1-error\" required><\/div><div id=\"wpforms-29301-field_18-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_18\">Country <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-29301-field_18\" class=\"wpforms-field-medium wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"1\" name=\"wpforms[fields][18]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Afghanistan\"  class=\"choice-4 depth-1\"  >Afghanistan<\/option><option value=\"Albanian\"  class=\"choice-5 depth-1\"  >Albanian<\/option><option value=\"Germany\"  class=\"choice-6 depth-1\"  >Germany<\/option><option value=\"Andorra\"  class=\"choice-7 depth-1\"  >Andorra<\/option><option value=\"Angola\"  class=\"choice-8 depth-1\"  >Angola<\/option><option value=\"Old and bearded\"  class=\"choice-9 depth-1\"  >Old and bearded<\/option><option value=\"Saudi Arabia \/ Saudi Arabia\"  class=\"choice-10 depth-1\"  >Saudi Arabia \/ Saudi Arabia<\/option><option value=\"Algeria\"  class=\"choice-11 depth-1\"  >Algeria<\/option><option value=\"Argentina\"  class=\"choice-12 depth-1\"  >Argentina<\/option><option value=\"Armenia\"  class=\"choice-13 depth-1\"  >Armenia<\/option><option value=\"Australia\"  class=\"choice-14 depth-1\"  >Australia<\/option><option value=\"Austria\"  class=\"choice-15 depth-1\"  >Austria<\/option><option value=\"Azerbaijan\"  class=\"choice-16 depth-1\"  >Azerbaijan<\/option><option value=\"Bahamas\"  class=\"choice-17 depth-1\"  >Bahamas<\/option><option value=\"Bangladesh\"  class=\"choice-18 depth-1\"  >Bangladesh<\/option><option value=\"barbados\"  class=\"choice-19 depth-1\"  >barbados<\/option><option value=\"bahrain\"  class=\"choice-20 depth-1\"  >bahrain<\/option><option value=\"Belgium\"  class=\"choice-21 depth-1\"  >Belgium<\/option><option value=\"belize\"  class=\"choice-22 depth-1\"  >belize<\/option><option value=\"belarus\"  class=\"choice-23 depth-1\"  >belarus<\/option><option value=\"Benin\"  class=\"choice-24 depth-1\"  >Benin<\/option><option value=\"Burma \/ Myanmar\"  class=\"choice-25 depth-1\"  >Burma \/ Myanmar<\/option><option value=\"bolivian\"  class=\"choice-26 depth-1\"  >bolivian<\/option><option value=\"Bosnia and Herzegovina \/ Bosnia-Herzegovina\"  class=\"choice-27 depth-1\"  >Bosnia and Herzegovina \/ Bosnia-Herzegovina<\/option><option value=\"botswana\"  class=\"choice-28 depth-1\"  >botswana<\/option><option value=\"Brazil\"  class=\"choice-29 depth-1\"  >Brazil<\/option><option value=\"brunei\"  class=\"choice-30 depth-1\"  >brunei<\/option><option value=\"Bulgaria\"  class=\"choice-31 depth-1\"  >Bulgaria<\/option><option value=\"Burkina Faso\"  class=\"choice-32 depth-1\"  >Burkina Faso<\/option><option value=\"Burundi\"  class=\"choice-33 depth-1\"  >Burundi<\/option><option value=\"bhutan\"  class=\"choice-34 depth-1\"  >bhutan<\/option><option value=\"Cape Verde\"  class=\"choice-35 depth-1\"  >Cape Verde<\/option><option value=\"Cambodia\"  class=\"choice-36 depth-1\"  >Cambodia<\/option><option value=\"Cameroon\"  class=\"choice-37 depth-1\"  >Cameroon<\/option><option value=\"Canada\"  class=\"choice-38 depth-1\"  >Canada<\/option><option value=\"Taste\"  class=\"choice-39 depth-1\"  >Taste<\/option><option value=\"Central African Republic\"  class=\"choice-40 depth-1\"  >Central African Republic<\/option><option value=\"Chad\"  class=\"choice-41 depth-1\"  >Chad<\/option><option value=\"Czech Republic \/ Czechia\"  class=\"choice-42 depth-1\"  >Czech Republic \/ Czechia<\/option><option value=\"Chili\"  class=\"choice-43 depth-1\"  >Chili<\/option><option value=\"China\"  class=\"choice-44 depth-1\"  >China<\/option><option value=\"Cyprus\"  class=\"choice-45 depth-1\"  >Cyprus<\/option><option value=\"Colombia\"  class=\"choice-46 depth-1\"  >Colombia<\/option><option value=\"comoros\"  class=\"choice-47 depth-1\"  >comoros<\/option><option value=\"Republic of Congo\"  class=\"choice-48 depth-1\"  >Republic of Congo<\/option><option value=\"Democratic Republic of Congo\"  class=\"choice-49 depth-1\"  >Democratic Republic of Congo<\/option><option value=\"North Korea\"  class=\"choice-50 depth-1\"  >North Korea<\/option><option value=\"South Korea\"  class=\"choice-51 depth-1\"  >South Korea<\/option><option value=\"Ivory Coast\"  class=\"choice-52 depth-1\"  >Ivory Coast<\/option><option value=\"Costa Rica\"  class=\"choice-53 depth-1\"  >Costa Rica<\/option><option value=\"Croatia\"  class=\"choice-54 depth-1\"  >Croatia<\/option><option value=\"Cuba\"  class=\"choice-55 depth-1\"  >Cuba<\/option><option value=\"Denmark\"  class=\"choice-56 depth-1\"  >Denmark<\/option><option value=\"Dominica\"  class=\"choice-57 depth-1\"  >Dominica<\/option><option value=\"Dominican Republic\"  class=\"choice-58 depth-1\"  >Dominican Republic<\/option><option value=\"Ecuador\"  class=\"choice-59 depth-1\"  >Ecuador<\/option><option value=\"Egypt\"  class=\"choice-60 depth-1\"  >Egypt<\/option><option value=\"The Savior\"  class=\"choice-61 depth-1\"  >The Savior<\/option><option value=\"United Arab Emirates\"  class=\"choice-62 depth-1\"  >United Arab Emirates<\/option><option value=\"eritrea\"  class=\"choice-63 depth-1\"  >eritrea<\/option><option value=\"Slovakia\"  class=\"choice-64 depth-1\"  >Slovakia<\/option><option value=\"Slovenia\"  class=\"choice-65 depth-1\"  >Slovenia<\/option><option value=\"Spain\"  class=\"choice-66 depth-1\"  >Spain<\/option><option value=\"USA\"  class=\"choice-67 depth-1\"  >USA<\/option><option value=\"Estonia\"  class=\"choice-68 depth-1\"  >Estonia<\/option><option value=\"Ethiopia\"  class=\"choice-69 depth-1\"  >Ethiopia<\/option><option value=\"Philippines\"  class=\"choice-70 depth-1\"  >Philippines<\/option><option value=\"Finland\"  class=\"choice-71 depth-1\"  >Finland<\/option><option value=\"fiji\"  class=\"choice-72 depth-1\"  >fiji<\/option><option value=\"France\"  class=\"choice-73 depth-1\"  >France<\/option><option value=\"Gabon\"  class=\"choice-74 depth-1\"  >Gabon<\/option><option value=\"Gambia\"  class=\"choice-75 depth-1\"  >Gambia<\/option><option value=\"Georgia\"  class=\"choice-76 depth-1\"  >Georgia<\/option><option value=\"Ghana\"  class=\"choice-77 depth-1\"  >Ghana<\/option><option value=\"Grenade\"  class=\"choice-78 depth-1\"  >Grenade<\/option><option value=\"Greece\"  class=\"choice-79 depth-1\"  >Greece<\/option><option value=\"Guatemala\"  class=\"choice-80 depth-1\"  >Guatemala<\/option><option value=\"Guinea\"  class=\"choice-81 depth-1\"  >Guinea<\/option><option value=\"Guinea-Bissau\"  class=\"choice-82 depth-1\"  >Guinea-Bissau<\/option><option value=\"Equatorial Guinea\"  class=\"choice-83 depth-1\"  >Equatorial Guinea<\/option><option value=\"guyana\"  class=\"choice-84 depth-1\"  >guyana<\/option><option value=\"Haiti\"  class=\"choice-85 depth-1\"  >Haiti<\/option><option value=\"Honduras\"  class=\"choice-86 depth-1\"  >Honduras<\/option><option value=\"Hungary\"  class=\"choice-87 depth-1\"  >Hungary<\/option><option value=\"India\"  class=\"choice-88 depth-1\"  >India<\/option><option value=\"Indonesia\"  class=\"choice-89 depth-1\"  >Indonesia<\/option><option value=\"Iraq\"  class=\"choice-90 depth-1\"  >Iraq<\/option><option value=\"Iran\"  class=\"choice-91 depth-1\"  >Iran<\/option><option value=\"Ireland\"  class=\"choice-92 depth-1\"  >Ireland<\/option><option value=\"Iceland\"  class=\"choice-93 depth-1\"  >Iceland<\/option><option value=\"Israel\"  class=\"choice-94 depth-1\"  >Israel<\/option><option value=\"Italy\"  class=\"choice-95 depth-1\"  >Italy<\/option><option value=\"Jamaica\"  class=\"choice-96 depth-1\"  >Jamaica<\/option><option value=\"Japan\"  class=\"choice-97 depth-1\"  >Japan<\/option><option value=\"Jordan\"  class=\"choice-98 depth-1\"  >Jordan<\/option><option value=\"Kazakhstan\"  class=\"choice-99 depth-1\"  >Kazakhstan<\/option><option value=\"Kenya\"  class=\"choice-100 depth-1\"  >Kenya<\/option><option value=\"Kyrgyzstan\"  class=\"choice-101 depth-1\"  >Kyrgyzstan<\/option><option value=\"Kiribati\"  class=\"choice-102 depth-1\"  >Kiribati<\/option><option value=\"Kuwait\"  class=\"choice-103 depth-1\"  >Kuwait<\/option><option value=\"Laos\"  class=\"choice-104 depth-1\"  >Laos<\/option><option value=\"Lesotho\"  class=\"choice-105 depth-1\"  >Lesotho<\/option><option value=\"Latvia\"  class=\"choice-106 depth-1\"  >Latvia<\/option><option value=\"Lebanon\"  class=\"choice-107 depth-1\"  >Lebanon<\/option><option value=\"Liberia\"  class=\"choice-108 depth-1\"  >Liberia<\/option><option value=\"Libya\"  class=\"choice-109 depth-1\"  >Libya<\/option><option value=\"liechtenstein\"  class=\"choice-110 depth-1\"  >liechtenstein<\/option><option value=\"Lithuania\"  class=\"choice-111 depth-1\"  >Lithuania<\/option><option value=\"Luxembourg\"  class=\"choice-112 depth-1\"  >Luxembourg<\/option><option value=\"North Macedonia\"  class=\"choice-113 depth-1\"  >North Macedonia<\/option><option value=\"Madagascar\"  class=\"choice-114 depth-1\"  >Madagascar<\/option><option value=\"Malaysia\"  class=\"choice-115 depth-1\"  >Malaysia<\/option><option value=\"Malawi\"  class=\"choice-116 depth-1\"  >Malawi<\/option><option value=\"Maldives\"  class=\"choice-117 depth-1\"  >Maldives<\/option><option value=\"Mali \/ Mali\"  class=\"choice-118 depth-1\"  >Mali \/ Mali<\/option><option value=\"malt\"  class=\"choice-119 depth-1\"  >malt<\/option><option value=\"Morocco\"  class=\"choice-120 depth-1\"  >Morocco<\/option><option value=\"Marshall Islands\"  class=\"choice-121 depth-1\"  >Marshall Islands<\/option><option value=\"Mauricio\"  class=\"choice-122 depth-1\"  >Mauricio<\/option><option value=\"Mauritania\"  class=\"choice-123 depth-1\"  >Mauritania<\/option><option value=\"Mexico\"  class=\"choice-124 depth-1\"  >Mexico<\/option><option value=\"micronesia\"  class=\"choice-125 depth-1\"  >micronesia<\/option><option value=\"moldova\"  class=\"choice-126 depth-1\"  >moldova<\/option><option value=\"Monaco\"  class=\"choice-127 depth-1\"  >Monaco<\/option><option value=\"Mongolia\"  class=\"choice-128 depth-1\"  >Mongolia<\/option><option value=\"Montenegro\"  class=\"choice-129 depth-1\"  >Montenegro<\/option><option value=\"Mozambique\"  class=\"choice-130 depth-1\"  >Mozambique<\/option><option value=\"Namibia\"  class=\"choice-131 depth-1\"  >Namibia<\/option><option value=\"Nauru\"  class=\"choice-132 depth-1\"  >Nauru<\/option><option value=\"Nepal\"  class=\"choice-133 depth-1\"  >Nepal<\/option><option value=\"Nicaragua\"  class=\"choice-134 depth-1\"  >Nicaragua<\/option><option value=\"Niger\"  class=\"choice-135 depth-1\"  >Niger<\/option><option value=\"Nigeria\"  class=\"choice-136 depth-1\"  >Nigeria<\/option><option value=\"Norway\"  class=\"choice-137 depth-1\"  >Norway<\/option><option value=\"New Zealand \/ New Zealand\"  class=\"choice-138 depth-1\"  >New Zealand \/ New Zealand<\/option><option value=\"Oman\"  class=\"choice-139 depth-1\"  >Oman<\/option><option value=\"Netherlands\"  class=\"choice-140 depth-1\"  >Netherlands<\/option><option value=\"Pakistan\"  class=\"choice-141 depth-1\"  >Pakistan<\/option><option value=\"Palau\"  class=\"choice-142 depth-1\"  >Palau<\/option><option value=\"Palestine\"  class=\"choice-143 depth-1\"  >Palestine<\/option><option value=\"Panama\"  class=\"choice-144 depth-1\"  >Panama<\/option><option value=\"Papua New Guinea\"  class=\"choice-145 depth-1\"  >Papua New Guinea<\/option><option value=\"Paraguayan\"  class=\"choice-146 depth-1\"  >Paraguayan<\/option><option value=\"Peru\"  class=\"choice-147 depth-1\"  >Peru<\/option><option value=\"Poland\"  class=\"choice-148 depth-1\"  >Poland<\/option><option value=\"Portugal\"  class=\"choice-149 depth-1\"  >Portugal<\/option><option value=\"United Kingdom\"  class=\"choice-150 depth-1\"  >United Kingdom<\/option><option value=\"Rwanda\"  class=\"choice-151 depth-1\"  >Rwanda<\/option><option value=\"Romania \/ Romania\"  class=\"choice-152 depth-1\"  >Romania \/ Romania<\/option><option value=\"Russia\"  class=\"choice-153 depth-1\"  >Russia<\/option><option value=\"Solomon Islands\"  class=\"choice-154 depth-1\"  >Solomon Islands<\/option><option value=\"samoa\"  class=\"choice-155 depth-1\"  >samoa<\/option><option value=\"Saint Kitts and Nevis\"  class=\"choice-156 depth-1\"  >Saint Kitts and Nevis<\/option><option value=\"San Marino\"  class=\"choice-157 depth-1\"  >San Marino<\/option><option value=\"St. Vincent and the Grenadines\"  class=\"choice-158 depth-1\"  >St. Vincent and the Grenadines<\/option><option value=\"St. Lucia\"  class=\"choice-159 depth-1\"  >St. Lucia<\/option><option value=\"Sao Tome and Principe\"  class=\"choice-160 depth-1\"  >Sao Tome and Principe<\/option><option value=\"Senegal\"  class=\"choice-161 depth-1\"  >Senegal<\/option><option value=\"Serbian\"  class=\"choice-162 depth-1\"  >Serbian<\/option><option value=\"seychelles\"  class=\"choice-163 depth-1\"  >seychelles<\/option><option value=\"Sierra Leone\"  class=\"choice-164 depth-1\"  >Sierra Leone<\/option><option value=\"Singapore\"  class=\"choice-165 depth-1\"  >Singapore<\/option><option value=\"Syria\"  class=\"choice-166 depth-1\"  >Syria<\/option><option value=\"Somalia\"  class=\"choice-167 depth-1\"  >Somalia<\/option><option value=\"Sri Lanka\"  class=\"choice-168 depth-1\"  >Sri Lanka<\/option><option value=\"Swaziland \/ Eswatini\"  class=\"choice-169 depth-1\"  >Swaziland \/ Eswatini<\/option><option value=\"South Africa\"  class=\"choice-170 depth-1\"  >South Africa<\/option><option value=\"Sudan\"  class=\"choice-171 depth-1\"  >Sudan<\/option><option value=\"South Sudan\"  class=\"choice-172 depth-1\"  >South Sudan<\/option><option value=\"Sweden\"  class=\"choice-173 depth-1\"  >Sweden<\/option><option value=\"Swiss\"  class=\"choice-174 depth-1\"  >Swiss<\/option><option value=\"Surinam\"  class=\"choice-175 depth-1\"  >Surinam<\/option><option value=\"thailand\"  class=\"choice-176 depth-1\"  >thailand<\/option><option value=\"Tanzania\"  class=\"choice-177 depth-1\"  >Tanzania<\/option><option value=\"Tajikistan\"  class=\"choice-178 depth-1\"  >Tajikistan<\/option><option value=\"East Timor\"  class=\"choice-179 depth-1\"  >East Timor<\/option><option value=\"Togo\"  class=\"choice-180 depth-1\"  >Togo<\/option><option value=\"Tonga\"  class=\"choice-181 depth-1\"  >Tonga<\/option><option value=\"Trinidad and Tobago\"  class=\"choice-182 depth-1\"  >Trinidad and Tobago<\/option><option value=\"Tunisia\"  class=\"choice-183 depth-1\"  >Tunisia<\/option><option value=\"Turkmenistan\"  class=\"choice-184 depth-1\"  >Turkmenistan<\/option><option value=\"T\u00fcrkiye\"  class=\"choice-185 depth-1\"  >T\u00fcrkiye<\/option><option value=\"Tuvalu\"  class=\"choice-186 depth-1\"  >Tuvalu<\/option><option value=\"Ukraine\"  class=\"choice-187 depth-1\"  >Ukraine<\/option><option value=\"Uganda\"  class=\"choice-188 depth-1\"  >Uganda<\/option><option value=\"Uruguay\"  class=\"choice-189 depth-1\"  >Uruguay<\/option><option value=\"uzbekistan\"  class=\"choice-190 depth-1\"  >uzbekistan<\/option><option value=\"Vanuatu\"  class=\"choice-191 depth-1\"  >Vanuatu<\/option><option value=\"Vatican City\"  class=\"choice-192 depth-1\"  >Vatican City<\/option><option value=\"Venezuela\"  class=\"choice-193 depth-1\"  >Venezuela<\/option><option value=\"Vietnam\"  class=\"choice-194 depth-1\"  >Vietnam<\/option><option value=\"Yemen\"  class=\"choice-195 depth-1\"  >Yemen<\/option><option value=\"djibouti\"  class=\"choice-196 depth-1\"  >djibouti<\/option><option value=\"Zambia\"  class=\"choice-197 depth-1\"  >Zambia<\/option><option value=\"Zimbabwe\"  class=\"choice-199 depth-1\"  >Zimbabwe<\/option><option value=\"Other\"  class=\"choice-200 depth-1\"  >Other<\/option><\/select><\/div><div id=\"wpforms-29301-field_23-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"23\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_23\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-29301-field_23\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][23]\" aria-label=\"Phone\" aria-errormessage=\"wpforms-29301-field_23-error\" required><\/div><div id=\"wpforms-29301-field_4-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_4\">Entry date <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-29301-field_4\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][4][date]\" aria-errormessage=\"wpforms-29301-field_4-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-29301-field_5-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_5\">Departure date <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-29301-field_5\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][5][date]\" aria-errormessage=\"wpforms-29301-field_5-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-29301-field_6-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_6\">Number of beds <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-29301-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" step=\"any\" aria-errormessage=\"wpforms-29301-field_6-error\" required><\/div><div id=\"wpforms-29301-field_8-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_8\">Amount of people <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-29301-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" step=\"any\" aria-errormessage=\"wpforms-29301-field_8-error\" required><\/div><div id=\"wpforms-29301-field_9-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_9\">Number of rooms <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-29301-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" step=\"any\" aria-errormessage=\"wpforms-29301-field_9-error\" required><\/div><div id=\"wpforms-29301-field_16-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-trigger\" data-field-id=\"16\"><fieldset><legend class=\"wpforms-field-label\">Airport Pickup<\/legend><ul id=\"wpforms-29301-field_16\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-29301-field_16_1\" name=\"wpforms[fields][16]\" value=\"Yes\" aria-errormessage=\"wpforms-29301-field_16_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-29301-field_16_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-29301-field_16_2\" name=\"wpforms[fields][16]\" value=\"No\" aria-errormessage=\"wpforms-29301-field_16_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-29301-field_16_2\">No<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-29301-field_19-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"19\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_19\">Airline and Flight Number<\/label><input type=\"text\" id=\"wpforms-29301-field_19\" class=\"wpforms-field-medium\" name=\"wpforms[fields][19]\" aria-errormessage=\"wpforms-29301-field_19-error\" ><\/div><div id=\"wpforms-29301-field_20-container\" class=\"wpforms-field wpforms-field-number-slider wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"20\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_20\">Number of passengers<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-29301-field_20\" class=\"wpforms-field-medium\" name=\"wpforms[fields][20]\" value=\"1\" aria-errormessage=\"wpforms-29301-field_20-error\"\t\tmin=\"1\"\n\tmax=\"10\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Valor seleccionado: {value}\">\n\tValor seleccionado: <b>1<\/b><\/div>\n<\/div><div id=\"wpforms-29301-field_21-container\" class=\"wpforms-field wpforms-field-date-time wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"21\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Date and Time of Collection <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-date-type-datepicker\"><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-29301-field_21\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][21][date]\" aria-errormessage=\"wpforms-29301-field_21-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><label for=\"wpforms-29301-field_21\" class=\"wpforms-field-sublabel after\">Date<\/label><\/div><div class=\"wpforms-field-row-block\"><input type=\"text\" id=\"wpforms-29301-field_21-time\" class=\"wpforms-field-date-time-time wpforms-timepicker wpforms-field-required\" data-time-format=\"g:i A\" data-step=\"30\" data-rule-time12h=\"true\" name=\"wpforms[fields][21][time]\" aria-errormessage=\"wpforms-29301-field_21-time-error\" required><label for=\"wpforms-29301-field_21-time\" class=\"wpforms-field-sublabel after\">Time<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-29301-field_22-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"22\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_22\">Destination address <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-29301-field_22\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][22]\" aria-errormessage=\"wpforms-29301-field_22-error\" required><\/div><div id=\"wpforms-29301-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-29301-field_2\">Message <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-29301-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-29301-field_2-error\" required><\/textarea><\/div><div id=\"wpforms-29301-field_24-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"24\"><div id=\"wpforms-29301-field_24\" aria-errormessage=\"wpforms-29301-field_24-error\"><div id=\"wpforms-40399-field_58-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"58\">\r\n\t<ul id=\"wpforms-40399-field_58\" class=\"wpforms-field-required\">\r\n\t\t<li class=\"choice-1 wpforms-selected\">\r\n\t\t<input type=\"checkbox\" id=\"wpforms-40399-field_58_1\" name=\"wpforms[fields][58][]\" value=\"Doy mi consentimiento para que esta web almacene la informaci\u00f3n que env\u00edo para que puedan responder a mi petici\u00f3n.\" aria-errormessage=\"wpforms-40399-field_58_1-error\" required=\"\" class=\"wpforms-valid\" aria-invalid=\"false\" aria-describedby=\"wpforms[fields][58][]-error\" checked\/>\r\n\t\t<label class=\"wpforms-field-label\" for=\"wpforms-40399-field_58\">I accept the  <a href=\"https:\/\/encuba.net\/en\/conditions-of-use-and-privacy-policies-encuba-net\/\" target=\"_blank\">Terms of Use or Privacy Policy<\/a> of the site<\/label><span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span>\r\n\t\t<\/li>\r\n\t<\/ul>\r\n<\/div>\r\n<\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"29301\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/estate_property\/48950\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-29301\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Send\" aria-live=\"assertive\" value=\"wpforms-submit\">Send<\/button><img decoding=\"async\" data-src=\"https:\/\/encuba.net\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner lazyload\" style=\"--smush-placeholder-width: 26px; --smush-placeholder-aspect-ratio: 26\/26;display: none;\" width=\"26\" height=\"26\" alt=\"Loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]The Apto Marina in Playa is an exclusive property that offers a comfortable and relaxing stay with stunning views of the Hemingway Marina. It has three bedrooms, each equipped with a private bathroom, hot water and minibar, as well as a TV for your entertainment. The kitchen is independent and perfect for preparing your favorite meals. In addition, it includes a grill to &#8230;<\/p>\n","protected":false},"featured_media":48946,"comment_status":"open","ping_status":"closed","template":"","property_category":[461],"property_action_category":[],"property_city":[],"property_area":[],"property_county_state":[],"property_features":[],"property_status":[],"class_list":["post-48950","estate_property","type-estate_property","status-publish","has-post-thumbnail","hentry","property_category-casas-en-santa-fe-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marina Apartment in Playa, 3 bedrooms and sea views<\/title>\n<meta name=\"description\" content=\"Enjoy the Marina Apartment in Playa, with 3 bedrooms each with bathroom and views of the Hemingway Marina. Book now this unique and relaxing accommodation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marina Apartment in Playa, 3 bedrooms and sea views\" \/>\n<meta property=\"og:description\" content=\"Enjoy the Marina Apartment in Playa, with 3 bedrooms each with bathroom and views of the Hemingway Marina. Book now this unique and relaxing accommodation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/\" \/>\n<meta property=\"og:site_name\" content=\"EnCUBA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-06T22:00:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/encuba.net\/wp-content\/uploads\/2025\/03\/Vistas-del-Apartamento-Marina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/marina-apartment-in-playa-3-bedrooms-and-sea-views\\\/\",\"url\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/marina-apartment-in-playa-3-bedrooms-and-sea-views\\\/\",\"name\":\"Marina Apartment in Playa, 3 bedrooms and sea views\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/marina-apartment-in-playa-3-bedrooms-and-sea-views\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/marina-apartment-in-playa-3-bedrooms-and-sea-views\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Vistas-del-Apartamento-Marina.jpg\",\"datePublished\":\"2025-03-06T19:06:21+00:00\",\"dateModified\":\"2025-03-06T22:00:51+00:00\",\"description\":\"Enjoy the Marina Apartment in Playa, with 3 bedrooms each with bathroom and views of the Hemingway Marina. Book now this unique and relaxing accommodation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/marina-apartment-in-playa-3-bedrooms-and-sea-views\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/marina-apartment-in-playa-3-bedrooms-and-sea-views\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/marina-apartment-in-playa-3-bedrooms-and-sea-views\\\/#primaryimage\",\"url\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Vistas-del-Apartamento-Marina.jpg\",\"contentUrl\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Vistas-del-Apartamento-Marina.jpg\",\"width\":1080,\"height\":810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/marina-apartment-in-playa-3-bedrooms-and-sea-views\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/encuba.net\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Properties\",\"item\":\"https:\\\/\\\/encuba.net\\\/en\\\/houses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marina Apartment in Playa, 3 bedrooms and sea views\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/encuba.net\\\/en\\\/\",\"name\":\"EnCUBA\",\"description\":\"Casas de alquiler en Cuba \ud83c\udfd8\ufe0f Renta de bellas casas particulares, apartamentos, habitaciones, villas y hostales. Reserva gratis y r\u00e1pido AQUI\",\"publisher\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/encuba.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#organization\",\"name\":\"EnCUBA\",\"url\":\"https:\\\/\\\/encuba.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo22.png\",\"contentUrl\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo22.png\",\"width\":192,\"height\":54,\"caption\":\"EnCUBA\"},\"image\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marina Apartment in Playa, 3 bedrooms and sea views","description":"Enjoy the Marina Apartment in Playa, with 3 bedrooms each with bathroom and views of the Hemingway Marina. Book now this unique and relaxing accommodation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/","og_locale":"en_US","og_type":"article","og_title":"Marina Apartment in Playa, 3 bedrooms and sea views","og_description":"Enjoy the Marina Apartment in Playa, with 3 bedrooms each with bathroom and views of the Hemingway Marina. Book now this unique and relaxing accommodation.","og_url":"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/","og_site_name":"EnCUBA","article_modified_time":"2025-03-06T22:00:51+00:00","og_image":[{"width":1080,"height":810,"url":"https:\/\/encuba.net\/wp-content\/uploads\/2025\/03\/Vistas-del-Apartamento-Marina.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/","url":"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/","name":"Marina Apartment in Playa, 3 bedrooms and sea views","isPartOf":{"@id":"https:\/\/encuba.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/#primaryimage"},"image":{"@id":"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/#primaryimage"},"thumbnailUrl":"https:\/\/encuba.net\/wp-content\/uploads\/2025\/03\/Vistas-del-Apartamento-Marina.jpg","datePublished":"2025-03-06T19:06:21+00:00","dateModified":"2025-03-06T22:00:51+00:00","description":"Enjoy the Marina Apartment in Playa, with 3 bedrooms each with bathroom and views of the Hemingway Marina. Book now this unique and relaxing accommodation.","breadcrumb":{"@id":"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/#primaryimage","url":"https:\/\/encuba.net\/wp-content\/uploads\/2025\/03\/Vistas-del-Apartamento-Marina.jpg","contentUrl":"https:\/\/encuba.net\/wp-content\/uploads\/2025\/03\/Vistas-del-Apartamento-Marina.jpg","width":1080,"height":810},{"@type":"BreadcrumbList","@id":"https:\/\/encuba.net\/en\/houses\/marina-apartment-in-playa-3-bedrooms-and-sea-views\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/encuba.net\/en\/"},{"@type":"ListItem","position":2,"name":"Properties","item":"https:\/\/encuba.net\/en\/houses\/"},{"@type":"ListItem","position":3,"name":"Marina Apartment in Playa, 3 bedrooms and sea views"}]},{"@type":"WebSite","@id":"https:\/\/encuba.net\/en\/#website","url":"https:\/\/encuba.net\/en\/","name":"EnCUBA","description":"Casas de alquiler en Cuba \ud83c\udfd8\ufe0f Renta de bellas casas particulares, apartamentos, habitaciones, villas y hostales. Reserva gratis y r\u00e1pido AQUI","publisher":{"@id":"https:\/\/encuba.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encuba.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/encuba.net\/en\/#organization","name":"EnCUBA","url":"https:\/\/encuba.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/encuba.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/04\/logo22.png","contentUrl":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/04\/logo22.png","width":192,"height":54,"caption":"EnCUBA"},"image":{"@id":"https:\/\/encuba.net\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/estate_property\/48950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/estate_property"}],"about":[{"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/types\/estate_property"}],"replies":[{"embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/comments?post=48950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/media\/48946"}],"wp:attachment":[{"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/media?parent=48950"}],"wp:term":[{"taxonomy":"property_category","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_category?post=48950"},{"taxonomy":"property_action_category","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_action_category?post=48950"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_city?post=48950"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_area?post=48950"},{"taxonomy":"property_county_state","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_county_state?post=48950"},{"taxonomy":"property_features","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_features?post=48950"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/encuba.net\/en\/wp-json\/wp\/v2\/property_status?post=48950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}