{"id":32014,"date":"2022-02-15T17:38:25","date_gmt":"2022-02-15T17:38:25","guid":{"rendered":"https:\/\/nueva.encuba.net\/casas\/hostal-don-pepe-en-playa-larga-cuba-casa-cerca-de-la-playa\/"},"modified":"2022-02-15T17:50:30","modified_gmt":"2022-02-15T17:50:30","slug":"hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage","status":"publish","type":"estate_property","link":"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/","title":{"rendered":"Hostal Don Pepe \u00e0 Playa Larga, Cuba. Maison pr\u00e8s de la plage"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]L\u2019Hostal Don Pepe est situ\u00e9 \u00e0 Playa Larga, \u00e0 Cuba. La maison est proche de la plage. Il dispose de quatre chambres climatis\u00e9es avec leurs salles de bains priv\u00e9es, jardin, bar et terrasse. Des services gastronomiques, un transfert depuis et vers l\u2019a\u00e9roport et une blanchisserie sont propos\u00e9s.[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0073e1;\"><strong><span style=\"font-family: verdana, geneva, sans-serif;\">MAISON DE LIVRE<\/span><\/strong><\/span><\/p>\n<p>[\/vc_column_text]<style id=\"wpforms-css-vars-29302\">\n\t\t\t\t#wpforms-29302 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-29302\"><form id=\"wpforms-form-29302\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"29302\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/estate_property\/32014\" data-token=\"848e9971715c7920544a3dd82659e10c\" data-token-time=\"1784087896\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-29302-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><fieldset><legend class=\"wpforms-field-label\">Pr\u00e9nom et nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-29302-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" aria-errormessage=\"wpforms-29302-field_0-error\" required><label for=\"wpforms-29302-field_0\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-29302-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" aria-errormessage=\"wpforms-29302-field_0-last-error\" required><label for=\"wpforms-29302-field_0-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-29302-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_1\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-29302-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-29302-field_1-error\" required><\/div><div id=\"wpforms-29302-field_19-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"19\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_19\">Pays <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-29302-field_19\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][19]\" required=\"required\"><option value=\"Afghanistan\"  class=\"choice-4 depth-1\"  >Afghanistan<\/option><option value=\"albanais\"  class=\"choice-5 depth-1\"  >albanais<\/option><option value=\"Allemagne\"  class=\"choice-6 depth-1\"  >Allemagne<\/option><option value=\"Andorre\"  class=\"choice-7 depth-1\"  >Andorre<\/option><option value=\"Angola\"  class=\"choice-8 depth-1\"  >Angola<\/option><option value=\"Antigua et Barbuda\"  class=\"choice-9 depth-1\"  >Antigua et Barbuda<\/option><option value=\"Arabie Saoudite \/ Arabie Saoudite\"  class=\"choice-10 depth-1\"  >Arabie Saoudite \/ Arabie Saoudite<\/option><option value=\"Alg\u00e9rie\"  class=\"choice-11 depth-1\"  >Alg\u00e9rie<\/option><option value=\"Argentine\"  class=\"choice-12 depth-1\"  >Argentine<\/option><option value=\"Arm\u00e9nie\"  class=\"choice-13 depth-1\"  >Arm\u00e9nie<\/option><option value=\"Australie\"  class=\"choice-14 depth-1\"  >Australie<\/option><option value=\"L&#039;Autriche\"  class=\"choice-15 depth-1\"  >L'Autriche<\/option><option value=\"Azerba\u00efdjan\"  class=\"choice-16 depth-1\"  >Azerba\u00efdjan<\/option><option value=\"Bahamas\"  class=\"choice-17 depth-1\"  >Bahamas<\/option><option value=\"Bengladesh\"  class=\"choice-18 depth-1\"  >Bengladesh<\/option><option value=\"la barbade\"  class=\"choice-19 depth-1\"  >la barbade<\/option><option value=\"bahre\u00efn\"  class=\"choice-20 depth-1\"  >bahre\u00efn<\/option><option value=\"Belgique\"  class=\"choice-21 depth-1\"  >Belgique<\/option><option value=\"b\u00e9lize\"  class=\"choice-22 depth-1\"  >b\u00e9lize<\/option><option value=\"bi\u00e9lorussie\"  class=\"choice-23 depth-1\"  >bi\u00e9lorussie<\/option><option value=\"B\u00e9nin\"  class=\"choice-24 depth-1\"  >B\u00e9nin<\/option><option value=\"Birmanie \/ Birmanie\"  class=\"choice-25 depth-1\"  >Birmanie \/ Birmanie<\/option><option value=\"bolivien\"  class=\"choice-26 depth-1\"  >bolivien<\/option><option value=\"Bosnie-Herz\u00e9govine \/ Bosnie-Herz\u00e9govine\"  class=\"choice-27 depth-1\"  >Bosnie-Herz\u00e9govine \/ Bosnie-Herz\u00e9govine<\/option><option value=\"botswana\"  class=\"choice-28 depth-1\"  >botswana<\/option><option value=\"Br\u00e9sil\"  class=\"choice-29 depth-1\"  >Br\u00e9sil<\/option><option value=\"brun\u00e9i\"  class=\"choice-30 depth-1\"  >brun\u00e9i<\/option><option value=\"Bulgarie\"  class=\"choice-31 depth-1\"  >Bulgarie<\/option><option value=\"Burkina Faso\"  class=\"choice-32 depth-1\"  >Burkina Faso<\/option><option value=\"Burundi\"  class=\"choice-33 depth-1\"  >Burundi<\/option><option value=\"bhoutan\"  class=\"choice-34 depth-1\"  >bhoutan<\/option><option value=\"Cap-Vert\"  class=\"choice-35 depth-1\"  >Cap-Vert<\/option><option value=\"Cambodge\"  class=\"choice-36 depth-1\"  >Cambodge<\/option><option value=\"Cameroun\"  class=\"choice-37 depth-1\"  >Cameroun<\/option><option value=\"Canada\"  class=\"choice-38 depth-1\"  >Canada<\/option><option value=\"Go\u00fbt\"  class=\"choice-39 depth-1\"  >Go\u00fbt<\/option><option value=\"R\u00e9publique Centrafricaine\"  class=\"choice-40 depth-1\"  >R\u00e9publique Centrafricaine<\/option><option value=\"Tchad\"  class=\"choice-41 depth-1\"  >Tchad<\/option><option value=\"R\u00e9publique tch\u00e8que \/ Tch\u00e9quie\"  class=\"choice-42 depth-1\"  >R\u00e9publique tch\u00e8que \/ Tch\u00e9quie<\/option><option value=\"le Chili\"  class=\"choice-43 depth-1\"  >le Chili<\/option><option value=\"Chine\"  class=\"choice-44 depth-1\"  >Chine<\/option><option value=\"Chypre\"  class=\"choice-45 depth-1\"  >Chypre<\/option><option value=\"La Colombie\"  class=\"choice-46 depth-1\"  >La Colombie<\/option><option value=\"comores\"  class=\"choice-47 depth-1\"  >comores<\/option><option value=\"R\u00e9publique du Congo\"  class=\"choice-48 depth-1\"  >R\u00e9publique du Congo<\/option><option value=\"R\u00e9publique d\u00e9mocratique du Congo\"  class=\"choice-49 depth-1\"  >R\u00e9publique d\u00e9mocratique du Congo<\/option><option value=\"Cor\u00e9e du Nord\"  class=\"choice-50 depth-1\"  >Cor\u00e9e du Nord<\/option><option value=\"Cor\u00e9e du sud\"  class=\"choice-51 depth-1\"  >Cor\u00e9e du sud<\/option><option value=\"C\u00f4te d&#039;Ivoire\"  class=\"choice-52 depth-1\"  >C\u00f4te d'Ivoire<\/option><option value=\"Costa Rica\"  class=\"choice-53 depth-1\"  >Costa Rica<\/option><option value=\"Croatie\"  class=\"choice-54 depth-1\"  >Croatie<\/option><option value=\"Cuba\"  class=\"choice-55 depth-1\"  >Cuba<\/option><option value=\"Danemark\"  class=\"choice-56 depth-1\"  >Danemark<\/option><option value=\"Dominique\"  class=\"choice-57 depth-1\"  >Dominique<\/option><option value=\"R\u00e9publique Dominicaine\"  class=\"choice-58 depth-1\"  >R\u00e9publique Dominicaine<\/option><option value=\"Equateur\"  class=\"choice-59 depth-1\"  >Equateur<\/option><option value=\"Egypte\"  class=\"choice-60 depth-1\"  >Egypte<\/option><option value=\"Le sauveur\"  class=\"choice-61 depth-1\"  >Le sauveur<\/option><option value=\"\u00c9mirats arabes unis\"  class=\"choice-62 depth-1\"  >\u00c9mirats arabes unis<\/option><option value=\"\u00c9rythr\u00e9e\"  class=\"choice-63 depth-1\"  >\u00c9rythr\u00e9e<\/option><option value=\"Slovaquie\"  class=\"choice-64 depth-1\"  >Slovaquie<\/option><option value=\"Slov\u00e9nie\"  class=\"choice-65 depth-1\"  >Slov\u00e9nie<\/option><option value=\"Espagne\"  class=\"choice-66 depth-1\"  >Espagne<\/option><option value=\"\u00c9tats Unis\"  class=\"choice-67 depth-1\"  >\u00c9tats Unis<\/option><option value=\"Estonie\"  class=\"choice-68 depth-1\"  >Estonie<\/option><option value=\"Ethiopie\"  class=\"choice-69 depth-1\"  >Ethiopie<\/option><option value=\"Philippines\"  class=\"choice-70 depth-1\"  >Philippines<\/option><option value=\"Finlande\"  class=\"choice-71 depth-1\"  >Finlande<\/option><option value=\"Fidji\"  class=\"choice-72 depth-1\"  >Fidji<\/option><option value=\"France\"  class=\"choice-73 depth-1\"  >France<\/option><option value=\"Gabon\"  class=\"choice-74 depth-1\"  >Gabon<\/option><option value=\"Gambie\"  class=\"choice-75 depth-1\"  >Gambie<\/option><option value=\"G\u00e9orgie\"  class=\"choice-76 depth-1\"  >G\u00e9orgie<\/option><option value=\"Ghana\"  class=\"choice-77 depth-1\"  >Ghana<\/option><option value=\"Grenade\"  class=\"choice-78 depth-1\"  >Grenade<\/option><option value=\"Gr\u00e8ce\"  class=\"choice-79 depth-1\"  >Gr\u00e8ce<\/option><option value=\"Guatemala\"  class=\"choice-80 depth-1\"  >Guatemala<\/option><option value=\"Guin\u00e9e\"  class=\"choice-81 depth-1\"  >Guin\u00e9e<\/option><option value=\"Guin\u00e9e-Bissau\"  class=\"choice-82 depth-1\"  >Guin\u00e9e-Bissau<\/option><option value=\"Guin\u00e9e \u00e9quatoriale\"  class=\"choice-83 depth-1\"  >Guin\u00e9e \u00e9quatoriale<\/option><option value=\"Guyane\"  class=\"choice-84 depth-1\"  >Guyane<\/option><option value=\"Ha\u00efti\"  class=\"choice-85 depth-1\"  >Ha\u00efti<\/option><option value=\"Honduras\"  class=\"choice-86 depth-1\"  >Honduras<\/option><option value=\"Hongrie\"  class=\"choice-87 depth-1\"  >Hongrie<\/option><option value=\"Inde\"  class=\"choice-88 depth-1\"  >Inde<\/option><option value=\"Indon\u00e9sie\"  class=\"choice-89 depth-1\"  >Indon\u00e9sie<\/option><option value=\"Irak\"  class=\"choice-90 depth-1\"  >Irak<\/option><option value=\"L&#039;Iran\"  class=\"choice-91 depth-1\"  >L'Iran<\/option><option value=\"Irlande\"  class=\"choice-92 depth-1\"  >Irlande<\/option><option value=\"Islande\"  class=\"choice-93 depth-1\"  >Islande<\/option><option value=\"Isra\u00ebl\"  class=\"choice-94 depth-1\"  >Isra\u00ebl<\/option><option value=\"Italie\"  class=\"choice-95 depth-1\"  >Italie<\/option><option value=\"Jama\u00efque\"  class=\"choice-96 depth-1\"  >Jama\u00efque<\/option><option value=\"Japon\"  class=\"choice-97 depth-1\"  >Japon<\/option><option value=\"Jordan\"  class=\"choice-98 depth-1\"  >Jordan<\/option><option value=\"Kazakhstan\"  class=\"choice-99 depth-1\"  >Kazakhstan<\/option><option value=\"Kenya\"  class=\"choice-100 depth-1\"  >Kenya<\/option><option value=\"Kirghizistan\"  class=\"choice-101 depth-1\"  >Kirghizistan<\/option><option value=\"Kiribati\"  class=\"choice-102 depth-1\"  >Kiribati<\/option><option value=\"Koweit\"  class=\"choice-103 depth-1\"  >Koweit<\/option><option value=\"Laos\"  class=\"choice-104 depth-1\"  >Laos<\/option><option value=\"Lesotho\"  class=\"choice-105 depth-1\"  >Lesotho<\/option><option value=\"Lettonie\"  class=\"choice-106 depth-1\"  >Lettonie<\/option><option value=\"Liban\"  class=\"choice-107 depth-1\"  >Liban<\/option><option value=\"Lib\u00e9ria\"  class=\"choice-108 depth-1\"  >Lib\u00e9ria<\/option><option value=\"Libye\"  class=\"choice-109 depth-1\"  >Libye<\/option><option value=\"liechtenstein\"  class=\"choice-110 depth-1\"  >liechtenstein<\/option><option value=\"Lituanie\"  class=\"choice-111 depth-1\"  >Lituanie<\/option><option value=\"Luxembourg\"  class=\"choice-112 depth-1\"  >Luxembourg<\/option><option value=\"Mac\u00e9doine du Nord\"  class=\"choice-113 depth-1\"  >Mac\u00e9doine du Nord<\/option><option value=\"Madagascar\"  class=\"choice-114 depth-1\"  >Madagascar<\/option><option value=\"Malaisie\"  class=\"choice-115 depth-1\"  >Malaisie<\/option><option value=\"Malawi\"  class=\"choice-116 depth-1\"  >Malawi<\/option><option value=\"Maldives\"  class=\"choice-117 depth-1\"  >Maldives<\/option><option value=\"Mali \/ Mali\"  class=\"choice-118 depth-1\"  >Mali \/ Mali<\/option><option value=\"malt\"  class=\"choice-119 depth-1\"  >malt<\/option><option value=\"Maroc\"  class=\"choice-120 depth-1\"  >Maroc<\/option><option value=\"Iles Marshall\"  class=\"choice-121 depth-1\"  >Iles Marshall<\/option><option value=\"Maurice\"  class=\"choice-122 depth-1\"  >Maurice<\/option><option value=\"Mauritanie\"  class=\"choice-123 depth-1\"  >Mauritanie<\/option><option value=\"Mexique\"  class=\"choice-124 depth-1\"  >Mexique<\/option><option value=\"micron\u00e9sie\"  class=\"choice-125 depth-1\"  >micron\u00e9sie<\/option><option value=\"la moldavie\"  class=\"choice-126 depth-1\"  >la moldavie<\/option><option value=\"Monaco\"  class=\"choice-127 depth-1\"  >Monaco<\/option><option value=\"Mongolie\"  class=\"choice-128 depth-1\"  >Mongolie<\/option><option value=\"Mont\u00e9n\u00e9gro\"  class=\"choice-129 depth-1\"  >Mont\u00e9n\u00e9gro<\/option><option value=\"Mozambique\"  class=\"choice-130 depth-1\"  >Mozambique<\/option><option value=\"Namibie\"  class=\"choice-131 depth-1\"  >Namibie<\/option><option value=\"Nauru\"  class=\"choice-132 depth-1\"  >Nauru<\/option><option value=\"N\u00e9pal\"  class=\"choice-133 depth-1\"  >N\u00e9pal<\/option><option value=\"Nicaragua\"  class=\"choice-134 depth-1\"  >Nicaragua<\/option><option value=\"Niger\"  class=\"choice-135 depth-1\"  >Niger<\/option><option value=\"Nigeria\"  class=\"choice-136 depth-1\"  >Nigeria<\/option><option value=\"Norv\u00e8ge\"  class=\"choice-137 depth-1\"  >Norv\u00e8ge<\/option><option value=\"Nouvelle-Z\u00e9lande \/ Nouvelle-Z\u00e9lande\"  class=\"choice-138 depth-1\"  >Nouvelle-Z\u00e9lande \/ Nouvelle-Z\u00e9lande<\/option><option value=\"Oman\"  class=\"choice-139 depth-1\"  >Oman<\/option><option value=\"Pays Bas\"  class=\"choice-140 depth-1\"  >Pays Bas<\/option><option value=\"Pakistan\"  class=\"choice-141 depth-1\"  >Pakistan<\/option><option value=\"Palaos\"  class=\"choice-142 depth-1\"  >Palaos<\/option><option value=\"Palestine\"  class=\"choice-143 depth-1\"  >Palestine<\/option><option value=\"Panama\"  class=\"choice-144 depth-1\"  >Panama<\/option><option value=\"Papouasie Nouvelle Guin\u00e9e\"  class=\"choice-145 depth-1\"  >Papouasie Nouvelle Guin\u00e9e<\/option><option value=\"paraguayen\"  class=\"choice-146 depth-1\"  >paraguayen<\/option><option value=\"P\u00e9rou\"  class=\"choice-147 depth-1\"  >P\u00e9rou<\/option><option value=\"Pologne\"  class=\"choice-148 depth-1\"  >Pologne<\/option><option value=\"le Portugal\"  class=\"choice-149 depth-1\"  >le Portugal<\/option><option value=\"Royaume-Uni\"  class=\"choice-150 depth-1\"  >Royaume-Uni<\/option><option value=\"Rwanda\"  class=\"choice-151 depth-1\"  >Rwanda<\/option><option value=\"Roumanie \/ Roumanie\"  class=\"choice-152 depth-1\"  >Roumanie \/ Roumanie<\/option><option value=\"Russie\"  class=\"choice-153 depth-1\"  >Russie<\/option><option value=\"Les \u00eeles Salomon\"  class=\"choice-154 depth-1\"  >Les \u00eeles Salomon<\/option><option value=\"samoa\"  class=\"choice-155 depth-1\"  >samoa<\/option><option value=\"Saint-Christophe-et-Ni\u00e9v\u00e8s\"  class=\"choice-156 depth-1\"  >Saint-Christophe-et-Ni\u00e9v\u00e8s<\/option><option value=\"Saint Marin\"  class=\"choice-157 depth-1\"  >Saint Marin<\/option><option value=\"Saint-Vincent-et-les Grenadines\"  class=\"choice-158 depth-1\"  >Saint-Vincent-et-les Grenadines<\/option><option value=\"Santa Lucia\"  class=\"choice-159 depth-1\"  >Santa Lucia<\/option><option value=\"Sao Tom\u00e9 et Principe\"  class=\"choice-160 depth-1\"  >Sao Tom\u00e9 et Principe<\/option><option value=\"S\u00e9n\u00e9gal\"  class=\"choice-161 depth-1\"  >S\u00e9n\u00e9gal<\/option><option value=\"serbe\"  class=\"choice-162 depth-1\"  >serbe<\/option><option value=\"les Seychelles\"  class=\"choice-163 depth-1\"  >les Seychelles<\/option><option value=\"Sierra Leone\"  class=\"choice-164 depth-1\"  >Sierra Leone<\/option><option value=\"Singapour\"  class=\"choice-165 depth-1\"  >Singapour<\/option><option value=\"Syrie\"  class=\"choice-166 depth-1\"  >Syrie<\/option><option value=\"Somalie\"  class=\"choice-167 depth-1\"  >Somalie<\/option><option value=\"Sri Lanka\"  class=\"choice-168 depth-1\"  >Sri Lanka<\/option><option value=\"Swaziland \/ Eswatini\"  class=\"choice-169 depth-1\"  >Swaziland \/ Eswatini<\/option><option value=\"Afrique du Sud\"  class=\"choice-170 depth-1\"  >Afrique du Sud<\/option><option value=\"Soudan\"  class=\"choice-171 depth-1\"  >Soudan<\/option><option value=\"Soudan du sud\"  class=\"choice-172 depth-1\"  >Soudan du sud<\/option><option value=\"Su\u00e8de\"  class=\"choice-173 depth-1\"  >Su\u00e8de<\/option><option value=\"Suisse\"  class=\"choice-174 depth-1\"  >Suisse<\/option><option value=\"Surinam\"  class=\"choice-175 depth-1\"  >Surinam<\/option><option value=\"Tha\u00eflande\"  class=\"choice-176 depth-1\"  >Tha\u00eflande<\/option><option value=\"Tanzanie\"  class=\"choice-177 depth-1\"  >Tanzanie<\/option><option value=\"Tadjikistan\"  class=\"choice-178 depth-1\"  >Tadjikistan<\/option><option value=\"Timor oriental\"  class=\"choice-179 depth-1\"  >Timor oriental<\/option><option value=\"Aller\"  class=\"choice-180 depth-1\"  >Aller<\/option><option value=\"Tonga\"  class=\"choice-181 depth-1\"  >Tonga<\/option><option value=\"Trinit\u00e9 et Tobago\"  class=\"choice-182 depth-1\"  >Trinit\u00e9 et Tobago<\/option><option value=\"Tunisie\"  class=\"choice-183 depth-1\"  >Tunisie<\/option><option value=\"Turkm\u00e9nistan\"  class=\"choice-184 depth-1\"  >Turkm\u00e9nistan<\/option><option value=\"Turquie\"  class=\"choice-185 depth-1\"  >Turquie<\/option><option value=\"Tuvalu\"  class=\"choice-186 depth-1\"  >Tuvalu<\/option><option value=\"Ukraine\"  class=\"choice-187 depth-1\"  >Ukraine<\/option><option value=\"Ouganda\"  class=\"choice-188 depth-1\"  >Ouganda<\/option><option value=\"Uruguay\"  class=\"choice-189 depth-1\"  >Uruguay<\/option><option value=\"Ouzb\u00e9kistan\"  class=\"choice-190 depth-1\"  >Ouzb\u00e9kistan<\/option><option value=\"Vanuatu\"  class=\"choice-191 depth-1\"  >Vanuatu<\/option><option value=\"Ville du Vatican\"  class=\"choice-192 depth-1\"  >Ville du Vatican<\/option><option value=\"Venezuela\"  class=\"choice-193 depth-1\"  >Venezuela<\/option><option value=\"Vi\u00eat Nam\"  class=\"choice-194 depth-1\"  >Vi\u00eat Nam<\/option><option value=\"Y\u00e9men\"  class=\"choice-195 depth-1\"  >Y\u00e9men<\/option><option value=\"Djibouti\"  class=\"choice-196 depth-1\"  >Djibouti<\/option><option value=\"Zambie\"  class=\"choice-197 depth-1\"  >Zambie<\/option><option value=\"Zimbabwe\"  class=\"choice-198 depth-1\"  >Zimbabwe<\/option><option value=\"Autre\"  class=\"choice-199 depth-1\"  >Autre<\/option><\/select><\/div><div id=\"wpforms-29302-field_24-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_24\">T\u00e9l\u00e9phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-29302-field_24\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][24]\" aria-label=\"T\u00e9l\u00e9phone\" aria-errormessage=\"wpforms-29302-field_24-error\" required><\/div><div id=\"wpforms-29302-field_4-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_4\">Date d&#039;entr\u00e9e <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-29302-field_4\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][4][date]\" aria-errormessage=\"wpforms-29302-field_4-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-29302-field_5-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_5\">Date de sortie <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-29302-field_5\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][5][date]\" aria-errormessage=\"wpforms-29302-field_5-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-29302-field_6-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_6\">Nombre de lits <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-29302-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" step=\"any\" aria-errormessage=\"wpforms-29302-field_6-error\" required><\/div><div id=\"wpforms-29302-field_8-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_8\">Quantit\u00e9 de personnes <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-29302-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" step=\"any\" aria-errormessage=\"wpforms-29302-field_8-error\" required><\/div><div id=\"wpforms-29302-field_9-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_9\">Nombre de chambres <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-29302-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" step=\"any\" aria-errormessage=\"wpforms-29302-field_9-error\" required><\/div><div id=\"wpforms-29302-field_16-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-trigger\" data-field-id=\"16\"><fieldset><legend class=\"wpforms-field-label\">Prise en charge \u00e0 l&#039;a\u00e9roport<\/legend><ul id=\"wpforms-29302-field_16\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-29302-field_16_1\" name=\"wpforms[fields][16]\" value=\"Ouais\" aria-errormessage=\"wpforms-29302-field_16_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-29302-field_16_1\">Ouais<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-29302-field_16_2\" name=\"wpforms[fields][16]\" value=\"Non\" aria-errormessage=\"wpforms-29302-field_16_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-29302-field_16_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-29302-field_20-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"20\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_20\">Compagnie a\u00e9rienne et num\u00e9ro de vol<\/label><input type=\"text\" id=\"wpforms-29302-field_20\" class=\"wpforms-field-medium\" name=\"wpforms[fields][20]\" aria-errormessage=\"wpforms-29302-field_20-error\" ><\/div><div id=\"wpforms-29302-field_21-container\" class=\"wpforms-field wpforms-field-number-slider wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"21\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_21\">Nombre de passagers<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-29302-field_21\" class=\"wpforms-field-medium\" name=\"wpforms[fields][21]\" value=\"1\" aria-errormessage=\"wpforms-29302-field_21-error\"\t\tmin=\"1\"\n\tmax=\"10\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Valor seleccionado: {value}\">\n\tValor seleccionado: <b>1<\/b><\/div>\n<\/div><div id=\"wpforms-29302-field_22-container\" class=\"wpforms-field wpforms-field-date-time wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"22\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Date et heure de collecte <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-date-type-datepicker\"><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-29302-field_22\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][22][date]\" aria-errormessage=\"wpforms-29302-field_22-error\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><label for=\"wpforms-29302-field_22\" class=\"wpforms-field-sublabel after\">Date<\/label><\/div><div class=\"wpforms-field-row-block\"><input type=\"text\" id=\"wpforms-29302-field_22-time\" class=\"wpforms-field-date-time-time wpforms-timepicker wpforms-field-required\" data-time-format=\"g:i A\" data-step=\"30\" data-rule-time12h=\"true\" name=\"wpforms[fields][22][time]\" aria-errormessage=\"wpforms-29302-field_22-time-error\" required><label for=\"wpforms-29302-field_22-time\" class=\"wpforms-field-sublabel after\">Heure<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-29302-field_23-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"23\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_23\">Adresse de destination <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-29302-field_23\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][23]\" aria-errormessage=\"wpforms-29302-field_23-error\" required><\/div><div id=\"wpforms-29302-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-29302-field_2\">Message <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-29302-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-29302-field_2-error\" required><\/textarea><\/div><div id=\"wpforms-29302-field_25-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"25\"><div id=\"wpforms-29302-field_25\" aria-errormessage=\"wpforms-29302-field_25-error\"><div id=\"wpforms-40399-field_58-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"58\">\r\n\t<ul id=\"wpforms-40399-field_58\" class=\"wpforms-field-required\">\r\n\t\t<li class=\"choice-1 wpforms-selected\">\r\n\t\t<input type=\"checkbox\" id=\"wpforms-40399-field_58_1\" name=\"wpforms[fields][58][]\" value=\"Doy mi consentimiento para que esta web almacene la informaci\u00f3n que env\u00edo para que puedan responder a mi petici\u00f3n.\" aria-errormessage=\"wpforms-40399-field_58_1-error\" required=\"\" class=\"wpforms-valid\" aria-invalid=\"false\" aria-describedby=\"wpforms[fields][58][]-error\" checked\/>\r\n\t\t<label class=\"wpforms-field-label\" for=\"wpforms-40399-field_58\">J'accepte les  <a href=\"https:\/\/encuba.net\/fr\/conditions-dutilisation-et-politique-de-confidentialite-encuba-net\/\" target=\"_blank\">conditions d'utilisation ou la politique de confidentialit\u00e9<\/a> du site<\/label><span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span>\r\n\t\t<\/li>\r\n\t<\/ul>\r\n<\/div>\r\n<\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"29302\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/estate_property\/32014\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-29302\" class=\"wpforms-submit\" data-alt-text=\"Envoi en cours...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img decoding=\"async\" data-src=\"https:\/\/encuba.net\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner lazyload\" style=\"--smush-placeholder-width: 26px; --smush-placeholder-aspect-ratio: 26\/26;display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]L\u2019Hostal Don Pepe est situ\u00e9 \u00e0 Playa Larga, \u00e0 Cuba. La maison est proche de la plage. Il dispose de quatre chambres climatis\u00e9es avec leurs salles de bains priv\u00e9es, jardin, bar et terrasse. Des services gastronomiques, un transfert depuis et vers l\u2019a\u00e9roport et une blanchisserie sont propos\u00e9s.[\/vc_column_text][vc_column_text] MAISON DE LIVRE [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"featured_media":32009,"comment_status":"open","ping_status":"closed","template":"","property_category":[234,225],"property_action_category":[],"property_city":[],"property_area":[],"property_county_state":[],"property_features":[],"property_status":[],"class_list":["post-32014","estate_property","type-estate_property","status-publish","has-post-thumbnail","hentry","property_category-playa-larga-fr","property_category-playas-de-cuba-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hostal Don Pepe \u00e0 Playa Larga, Cuba. Maison pr\u00e8s de la plage<\/title>\n<meta name=\"description\" content=\"R\u00e9servez \u00e0 l\u2019hostal Don Pepe \u00e0 Playa Larga, Cuba. Profitez d\u2019une maison pr\u00e8s de la plage.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hostal Don Pepe \u00e0 Playa Larga, Cuba. Maison pr\u00e8s de la plage\" \/>\n<meta property=\"og:description\" content=\"R\u00e9servez \u00e0 l\u2019hostal Don Pepe \u00e0 Playa Larga, Cuba. Profitez d\u2019une maison pr\u00e8s de la plage.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/\" \/>\n<meta property=\"og:site_name\" content=\"EnCUBA\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-15T17:50:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/encuba.net\/wp-content\/uploads\/2022\/02\/Hostal-Don-Pepe-en-Playa-Larga-Cuba..png\" \/>\n\t<meta property=\"og:image:width\" content=\"718\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/maisons\\\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\\\/\",\"url\":\"https:\\\/\\\/encuba.net\\\/fr\\\/maisons\\\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\\\/\",\"name\":\"Hostal Don Pepe \u00e0 Playa Larga, Cuba. Maison pr\u00e8s de la plage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/maisons\\\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/maisons\\\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Hostal-Don-Pepe-en-Playa-Larga-Cuba..png\",\"datePublished\":\"2022-02-15T17:38:25+00:00\",\"dateModified\":\"2022-02-15T17:50:30+00:00\",\"description\":\"R\u00e9servez \u00e0 l\u2019hostal Don Pepe \u00e0 Playa Larga, Cuba. Profitez d\u2019une maison pr\u00e8s de la plage.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/maisons\\\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/encuba.net\\\/fr\\\/maisons\\\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/maisons\\\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Hostal-Don-Pepe-en-Playa-Larga-Cuba..png\",\"contentUrl\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Hostal-Don-Pepe-en-Playa-Larga-Cuba..png\",\"width\":718,\"height\":536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/maisons\\\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/encuba.net\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propri\u00e9t\u00e9s\",\"item\":\"https:\\\/\\\/encuba.net\\\/fr\\\/maisons\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hostal Don Pepe \u00e0 Playa Larga, Cuba. Maison pr\u00e8s de la plage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/encuba.net\\\/fr\\\/\",\"name\":\"EnCUBA\",\"description\":\"Casas de alquiler en Cuba \ud83c\udfd8\ufe0f Renta de bellas casas particulares, apartamentos, habitaciones, villas y hostales. Reserva gratis y r\u00e1pido AQUI\",\"publisher\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/encuba.net\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/#organization\",\"name\":\"EnCUBA\",\"url\":\"https:\\\/\\\/encuba.net\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo22.png\",\"contentUrl\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo22.png\",\"width\":192,\"height\":54,\"caption\":\"EnCUBA\"},\"image\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hostal Don Pepe \u00e0 Playa Larga, Cuba. Maison pr\u00e8s de la plage","description":"R\u00e9servez \u00e0 l\u2019hostal Don Pepe \u00e0 Playa Larga, Cuba. Profitez d\u2019une maison pr\u00e8s de la plage.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/","og_locale":"fr_FR","og_type":"article","og_title":"Hostal Don Pepe \u00e0 Playa Larga, Cuba. Maison pr\u00e8s de la plage","og_description":"R\u00e9servez \u00e0 l\u2019hostal Don Pepe \u00e0 Playa Larga, Cuba. Profitez d\u2019une maison pr\u00e8s de la plage.","og_url":"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/","og_site_name":"EnCUBA","article_modified_time":"2022-02-15T17:50:30+00:00","og_image":[{"width":718,"height":536,"url":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/02\/Hostal-Don-Pepe-en-Playa-Larga-Cuba..png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/","url":"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/","name":"Hostal Don Pepe \u00e0 Playa Larga, Cuba. Maison pr\u00e8s de la plage","isPartOf":{"@id":"https:\/\/encuba.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/#primaryimage"},"image":{"@id":"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/#primaryimage"},"thumbnailUrl":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/02\/Hostal-Don-Pepe-en-Playa-Larga-Cuba..png","datePublished":"2022-02-15T17:38:25+00:00","dateModified":"2022-02-15T17:50:30+00:00","description":"R\u00e9servez \u00e0 l\u2019hostal Don Pepe \u00e0 Playa Larga, Cuba. Profitez d\u2019une maison pr\u00e8s de la plage.","breadcrumb":{"@id":"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/#primaryimage","url":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/02\/Hostal-Don-Pepe-en-Playa-Larga-Cuba..png","contentUrl":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/02\/Hostal-Don-Pepe-en-Playa-Larga-Cuba..png","width":718,"height":536},{"@type":"BreadcrumbList","@id":"https:\/\/encuba.net\/fr\/maisons\/hostal-don-pepe-a-playa-larga-cuba-maison-pres-de-la-plage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/encuba.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Propri\u00e9t\u00e9s","item":"https:\/\/encuba.net\/fr\/maisons\/"},{"@type":"ListItem","position":3,"name":"Hostal Don Pepe \u00e0 Playa Larga, Cuba. Maison pr\u00e8s de la plage"}]},{"@type":"WebSite","@id":"https:\/\/encuba.net\/fr\/#website","url":"https:\/\/encuba.net\/fr\/","name":"EnCUBA","description":"Casas de alquiler en Cuba \ud83c\udfd8\ufe0f Renta de bellas casas particulares, apartamentos, habitaciones, villas y hostales. Reserva gratis y r\u00e1pido AQUI","publisher":{"@id":"https:\/\/encuba.net\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encuba.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/encuba.net\/fr\/#organization","name":"EnCUBA","url":"https:\/\/encuba.net\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/encuba.net\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/04\/logo22.png","contentUrl":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/04\/logo22.png","width":192,"height":54,"caption":"EnCUBA"},"image":{"@id":"https:\/\/encuba.net\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/estate_property\/32014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/estate_property"}],"about":[{"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/types\/estate_property"}],"replies":[{"embeddable":true,"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/comments?post=32014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/media\/32009"}],"wp:attachment":[{"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/media?parent=32014"}],"wp:term":[{"taxonomy":"property_category","embeddable":true,"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/property_category?post=32014"},{"taxonomy":"property_action_category","embeddable":true,"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/property_action_category?post=32014"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/property_city?post=32014"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/property_area?post=32014"},{"taxonomy":"property_county_state","embeddable":true,"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/property_county_state?post=32014"},{"taxonomy":"property_features","embeddable":true,"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/property_features?post=32014"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/encuba.net\/fr\/wp-json\/wp\/v2\/property_status?post=32014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}