{"id":43927,"date":"2022-02-28T19:11:23","date_gmt":"2022-02-28T19:11:23","guid":{"rendered":"https:\/\/encuba.net\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\/"},"modified":"2024-02-06T04:46:40","modified_gmt":"2024-02-06T04:46:40","slug":"casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti","status":"publish","type":"page","link":"https:\/\/encuba.net\/it\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\/","title":{"rendered":"Casas Particulares con piscina a Santa Maria, L&#8217;Avana, Cuba. Appartamenti"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Prenotate qui case private con piscina a Santa Maria, L&#8217;Avana, Cuba. Vi offriamo un&#8217;ampia gamma di appartamenti in affitto, camere in ostelli e ville alla portata di tutte le tasche. I nostri alloggi a Santa Maria dispongono di tutti i comfort per un soggiorno confortevole durante le vostre vacanze.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;][vc_text_separator title=&#8221;CAMBIARE LA VALUTA&#8221; title_align=&#8221;separator_align_left&#8221; color=&#8221;blue&#8221; border_width=&#8221;4&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1682334718636{margin-top: -20px !important;}&#8221;][vc_widget_sidebar sidebar_id=&#8221;header4-widget-area&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Prenotate qui case private con piscina a Santa Maria, L&#8217;Avana, Cuba. Vi offriamo un&#8217;ampia gamma di appartamenti in affitto, camere in ostelli e ville alla portata di tutte le tasche. I nostri alloggi a Santa Maria dispongono di tutti i comfort per un soggiorno confortevole durante le vostre vacanze.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;][vc_text_separator title=&#8221;CAMBIARE LA VALUTA&#8221; title_align=&#8221;separator_align_left&#8221; color=&#8221;blue&#8221; border_width=&#8221;4&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1682334718636{margin-top: -20px !important;}&#8221;][vc_widget_sidebar sidebar_id=&#8221;header4-widget-area&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/property_list.php","meta":{"inline_featured_image":false,"_joinchat":[],"footnotes":""},"class_list":["post-43927","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casas Particulares con piscina a Santa Maria, L&#039;Avana, Cuba. Appartamenti<\/title>\n<meta name=\"description\" content=\"Prenotate qui case private con piscina a Santa Maria, L&#039;Avana, Cuba. Vi offriamo bellissimi appartamenti, ostelli e ville a prezzi vantaggiosi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encuba.net\/it\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casas Particulares con piscina a Santa Maria, L&#039;Avana, Cuba. Appartamenti\" \/>\n<meta property=\"og:description\" content=\"Prenotate qui case private con piscina a Santa Maria, L&#039;Avana, Cuba. Vi offriamo bellissimi appartamenti, ostelli e ville a prezzi vantaggiosi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encuba.net\/it\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\/\" \/>\n<meta property=\"og:site_name\" content=\"EnCUBA\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-06T04:46:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/encuba.net\\\/it\\\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\\\/\",\"url\":\"https:\\\/\\\/encuba.net\\\/it\\\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\\\/\",\"name\":\"Casas Particulares con piscina a Santa Maria, L'Avana, Cuba. Appartamenti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/it\\\/#website\"},\"datePublished\":\"2022-02-28T19:11:23+00:00\",\"dateModified\":\"2024-02-06T04:46:40+00:00\",\"description\":\"Prenotate qui case private con piscina a Santa Maria, L'Avana, Cuba. Vi offriamo bellissimi appartamenti, ostelli e ville a prezzi vantaggiosi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/it\\\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/encuba.net\\\/it\\\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/encuba.net\\\/it\\\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/encuba.net\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casas Particulares con piscina a Santa Maria, L&#8217;Avana, Cuba. Appartamenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/encuba.net\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/encuba.net\\\/it\\\/\",\"name\":\"EnCUBA\",\"description\":\"Casas de alquiler en Cuba \ud83c\udfd8\ufe0f Renta de bellas casas particulares, apartamentos, habitaciones, villas y hostales. Reserva gratis y r\u00e1pido AQUI\",\"publisher\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/encuba.net\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/encuba.net\\\/it\\\/#organization\",\"name\":\"EnCUBA\",\"url\":\"https:\\\/\\\/encuba.net\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/encuba.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo22.png\",\"contentUrl\":\"https:\\\/\\\/encuba.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo22.png\",\"width\":192,\"height\":54,\"caption\":\"EnCUBA\"},\"image\":{\"@id\":\"https:\\\/\\\/encuba.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casas Particulares con piscina a Santa Maria, L'Avana, Cuba. Appartamenti","description":"Prenotate qui case private con piscina a Santa Maria, L'Avana, Cuba. Vi offriamo bellissimi appartamenti, ostelli e ville a prezzi vantaggiosi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encuba.net\/it\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\/","og_locale":"it_IT","og_type":"article","og_title":"Casas Particulares con piscina a Santa Maria, L'Avana, Cuba. Appartamenti","og_description":"Prenotate qui case private con piscina a Santa Maria, L'Avana, Cuba. Vi offriamo bellissimi appartamenti, ostelli e ville a prezzi vantaggiosi.","og_url":"https:\/\/encuba.net\/it\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\/","og_site_name":"EnCUBA","article_modified_time":"2024-02-06T04:46:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/encuba.net\/it\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\/","url":"https:\/\/encuba.net\/it\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\/","name":"Casas Particulares con piscina a Santa Maria, L'Avana, Cuba. Appartamenti","isPartOf":{"@id":"https:\/\/encuba.net\/it\/#website"},"datePublished":"2022-02-28T19:11:23+00:00","dateModified":"2024-02-06T04:46:40+00:00","description":"Prenotate qui case private con piscina a Santa Maria, L'Avana, Cuba. Vi offriamo bellissimi appartamenti, ostelli e ville a prezzi vantaggiosi.","breadcrumb":{"@id":"https:\/\/encuba.net\/it\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/encuba.net\/it\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/encuba.net\/it\/casas-particulares-con-piscina-a-santa-maria-lavana-cuba-appartamenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/encuba.net\/it\/"},{"@type":"ListItem","position":2,"name":"Casas Particulares con piscina a Santa Maria, L&#8217;Avana, Cuba. Appartamenti"}]},{"@type":"WebSite","@id":"https:\/\/encuba.net\/it\/#website","url":"https:\/\/encuba.net\/it\/","name":"EnCUBA","description":"Casas de alquiler en Cuba \ud83c\udfd8\ufe0f Renta de bellas casas particulares, apartamentos, habitaciones, villas y hostales. Reserva gratis y r\u00e1pido AQUI","publisher":{"@id":"https:\/\/encuba.net\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encuba.net\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/encuba.net\/it\/#organization","name":"EnCUBA","url":"https:\/\/encuba.net\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/encuba.net\/it\/#\/schema\/logo\/image\/","url":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/04\/logo22.png","contentUrl":"https:\/\/encuba.net\/wp-content\/uploads\/2022\/04\/logo22.png","width":192,"height":54,"caption":"EnCUBA"},"image":{"@id":"https:\/\/encuba.net\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/encuba.net\/it\/wp-json\/wp\/v2\/pages\/43927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encuba.net\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/encuba.net\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/encuba.net\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/encuba.net\/it\/wp-json\/wp\/v2\/comments?post=43927"}],"version-history":[{"count":0,"href":"https:\/\/encuba.net\/it\/wp-json\/wp\/v2\/pages\/43927\/revisions"}],"wp:attachment":[{"href":"https:\/\/encuba.net\/it\/wp-json\/wp\/v2\/media?parent=43927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}